{"id":15774,"date":"2014-06-12T13:24:16","date_gmt":"2014-06-12T15:24:16","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15774"},"modified":"2014-06-12T13:24:16","modified_gmt":"2014-06-12T15:24:16","slug":"estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/","title":{"rendered":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15775\" alt=\"6360240w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w-360x229.jpg\" width=\"360\" height=\"229\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w-360x229.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w-650x414.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w-768x489.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w-150x95.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w-450x286.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w-696x443.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w-660x420.jpg 660w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w-269x170.jpg 269w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Madrid, 12 jun (EFE).- La cartelera espa\u00f1ola se renueva con t\u00edtulos para todos los p\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en \u00abS\u00f3lo los amantes sobreviven\u00bb, la \u00faltima versi\u00f3n animada de \u00abTarz\u00e1n\u00bb y el suspense del \u00abthriller\u00bb \u00abLas dos caras de enero\u00bb, con Viggo Mortensen y Kirsten Dunst.<\/p>\n<p><strong><em>SOLO LOS AMANTES Y LOS VAMPIROS SOBREVIVEN<\/em><\/strong><\/p>\n<p>El director de culto Jim Jarmusch vuelve a las pantallas con \u00abS\u00f3lo los amantes sobreviven\u00bb, una singular pel\u00edcula de vampiros modernos que cuenta con el protagonismo de Tilda Swinton (\u00abEl curioso caso de Benjamin Button\u00bb) y Tom Hiddleston (\u00abThor\u00bb), y que gan\u00f3 en el Festival de Sitges el Premio Especial del Jurado.<\/p>\n<p>La oscuridad de la noche, la m\u00fasica y el romanticismo se cruzan en una cinta repleta de ambientes melanc\u00f3licos y on\u00edricos que narra el reencuentro de dos amantes vampiros, que viv\u00edan distanciados en T\u00e1nger y Detroit, y cuya relaci\u00f3n se ver\u00e1 afectada por una tercera persona que amenaza con romper su amor.<\/p>\n<p><strong><em>SUSPENSE Y HUIDAS EN \u00abLAS DOS CARAS DE ENERO\u00bb<\/em><\/strong><\/p>\n<p>Tras un crimen fortuito sucedido en Grecia, un estafador y su mujer, ambos estadounidenses, deber\u00e1n confiar en un extra\u00f1o profesor para tratar de huir a Turqu\u00eda y escapar tanto de la ley como de su oscuro pasado.<\/p>\n<p>Adaptaci\u00f3n de una novela de Patricia Highsmith, \u00abLas dos caras de enero\u00bb es un tenso \u00abthriller\u00bb protagonizado por Viggo Mortensen (\u00abEl se\u00f1or de los anillos\u00bb) y Kirsten Dunst (\u00abMar\u00eda Antonieta\u00bb), dirigido por Hossein Amini (guionista de \u00abDrive\u00bb) y que adem\u00e1s cuenta con la m\u00fasica del espa\u00f1ol Alberto Iglesias.<\/p>\n<p><strong><em>EL REGRESO DE \u00abTARZ\u00c1N\u00bb<\/em><\/strong><\/p>\n<p>El m\u00edtico personaje criado en la selva que Johnny Weissmuller elev\u00f3 al estrellato, vuelve ahora con una pel\u00edcula de animaci\u00f3n que ha dirigido Reinhard Klooss utilizando la t\u00e9cnica de \u00abcaptura de movimiento\u00bb con actores reales.<\/p>\n<p>El argumento de esta producci\u00f3n germano-franco-estadounidense presenta a Tarz\u00e1n, criado en la selva tras el accidente de avi\u00f3n en el que murieron sus padres y que deber\u00e1 enfrentarse a la malvada corporaci\u00f3n Greystoke Energies y sus planes para saquear la naturaleza.<\/p>\n<p><strong><em>RISAS Y ENREDOS EN \u00abNO HAY DOS SIN TRES\u00bb<\/em><\/strong><\/p>\n<p>El director de \u00abEl diario de Noa\u00bb, Nick Cassavetes, se pasa a la comedia en una cinta de equ\u00edvocos y risas protagonizada por Cameron D\u00edaz (\u00abAlgo pasa con Mary\u00bb), Leslie Mann (\u00abSi fuera f\u00e1cil\u00bb) y la modelo Kate Upton, en su primer papel principal en el cine.<\/p>\n<p>Mark lleva una triple vida: est\u00e1 casado con Kate (Leslie Mann), sale en secreto con Carly (Cameron D\u00edaz) y tiene una tercera amante llamada Amber (Kate Upton). Cuando las tres mujeres se enteran de la situaci\u00f3n, planear\u00e1n conjuntamente una venganza contra \u00e9l.<\/p>\n<p><strong><em>INTENSO BIOPIC DE \u00abVIOLETTE\u00bb LEDUC<\/em><\/strong><\/p>\n<p>La intensa vida de la escritora francesa Violette Leduc llega a las pantallas de la mano del director Martin Provost (\u00abS\u00e9raphine\u00bb), quien presenta en el papel protagonista a la actriz Emmanuelle Devos.<\/p>\n<p>Violette Leduc, hija ileg\u00edtima de un noble, conoce en Par\u00eds a Simone de Beauvoir, quien la introducir\u00e1 en los c\u00edrculos intelectuales de la capital francesa y ver\u00e1 su extraordinario potencial para convertirse en una de las pioneras escritoras feministas.<\/p>\n<p><strong><em>\u00abTE FALTA CHISPA\u00bb PARA EL AMOR<\/em><\/strong><\/p>\n<p>El t\u00edmido y aburrido Stefan escucha un d\u00eda que su vecina Hayley quiere como pareja a un hombre que sea, sobre todo, muy divertido. Para enamorarla, Stefan iniciar\u00e1 un curso de aprendizaje acelerado con el objetivo de seducirla a trav\u00e9s de la risa.<\/p>\n<p>Simp\u00e1tica comedia dirigida por la debutante Lauralee Farrer con un elenco no muy conocido que lidera Tony Hale, quien interpret\u00f3 el papel del peculiar Buster Bluth en la serie de comedia \u00abArrested development\u00bb.<\/p>\n<p><strong><em>\u00abMETEORA\u00bb Y LA SOLEDAD DE UN MONASTERIO<\/em><\/strong><\/p>\n<p>Un hombre y una mujer, ambos recluidos en dos monasterios vecinos, idean un sistema de comunicaci\u00f3n a trav\u00e9s de espejos para escapar de la soledad.<\/p>\n<p>El director grecocolombiano Spiros Stathoulopoulos compiti\u00f3 en el Festival de Berl\u00edn con \u00abMeteora\u00bb, un original largometraje en el que destacan los impresionantes paisajes y la incorporaci\u00f3n de fragmentos de animaci\u00f3n.<\/p>\n<p><strong><em>EXILIADOS REPUBLICANOS EN \u00abCAMARADAS\u00bb<\/em><\/strong><\/p>\n<p>Tras el final de la Guerra Civil, numerosos republicanos espa\u00f1oles cruzaron la frontera para luchar en Francia contra el avance de Hitler. Pocos a\u00f1os despu\u00e9s de la victoria en la II Guerra Mundial, una operaci\u00f3n de la CIA y los servicios secretos franceses detendr\u00eda y expulsar\u00eda a muchos de esos exiliados.<\/p>\n<p>El documental \u00abCamaradas\u00bb, dirigido por Sabin Egilior, rastrea sus vidas a trav\u00e9s de la investigaci\u00f3n y recuperaci\u00f3n de testimonios personales y ser\u00e1 estrenado en salas de Bilbao, San Sebasti\u00e1n, Vitoria y Madrid.<\/p>\n<p>Marisa Montiel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 12 jun (EFE).- La cartelera espa\u00f1ola se renueva con t\u00edtulos para todos los p\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en \u00abS\u00f3lo los amantes sobreviven\u00bb, la \u00faltima versi\u00f3n animada de \u00abTarz\u00e1n\u00bb y el suspense del \u00abthriller\u00bb \u00abLas dos caras de enero\u00bb, con Viggo Mortensen y Kirsten Dunst. SOLO LOS AMANTES Y<\/p>\n","protected":false},"author":1,"featured_media":15775,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15774","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 12 jun (EFE).- La cartelera espa\u00f1ola se renueva con t\u00edtulos para todos los p\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en &quot;S\u00f3lo los amantes sobreviven&quot;, la \u00faltima versi\u00f3n animada de &quot;Tarz\u00e1n&quot; y el suspense del &quot;thriller&quot; &quot;Las dos caras de enero&quot;, con Viggo Mortensen y Kirsten Dunst. SOLO LOS AMANTES Y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 12 jun (EFE).- La cartelera espa\u00f1ola se renueva con t\u00edtulos para todos los p\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en &quot;S\u00f3lo los amantes sobreviven&quot;, la \u00faltima versi\u00f3n animada de &quot;Tarz\u00e1n&quot; y el suspense del &quot;thriller&quot; &quot;Las dos caras de enero&quot;, con Viggo Mortensen y Kirsten Dunst. SOLO LOS AMANTES Y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"509\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-12T15:24:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-12T15:24:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 12 jun (EFE).- La cartelera espa\u00f1ola se renueva con t\u00edtulos para todos los p\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en &quot;S\u00f3lo los amantes sobreviven&quot;, la \u00faltima versi\u00f3n animada de &quot;Tarz\u00e1n&quot; y el suspense del &quot;thriller&quot; &quot;Las dos caras de enero&quot;, con Viggo Mortensen y Kirsten Dunst. SOLO LOS AMANTES Y\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#article\",\"name\":\"Estrenos de la semana : Vampiros modernos y un tenso \\u00abthriller\\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias\",\"headline\":\"Estrenos de la semana : Vampiros modernos y un tenso \\u00abthriller\\u00bb con Viggo Mortensen, en los cines\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6360240w.jpg\",\"width\":800,\"height\":509},\"datePublished\":\"2014-06-12T13:24:16+02:00\",\"dateModified\":\"2014-06-12T13:24:16+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#listItem\",\"name\":\"Estrenos de la semana : Vampiros modernos y un tenso \\u00abthriller\\u00bb con Viggo Mortensen, en los cines\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#listItem\",\"position\":3,\"name\":\"Estrenos de la semana : Vampiros modernos y un tenso \\u00abthriller\\u00bb con Viggo Mortensen, en los cines\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/\",\"name\":\"Estrenos de la semana : Vampiros modernos y un tenso \\u00abthriller\\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias\",\"description\":\"Madrid, 12 jun (EFE).- La cartelera espa\\u00f1ola se renueva con t\\u00edtulos para todos los p\\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en \\\"S\\u00f3lo los amantes sobreviven\\\", la \\u00faltima versi\\u00f3n animada de \\\"Tarz\\u00e1n\\\" y el suspense del \\\"thriller\\\" \\\"Las dos caras de enero\\\", con Viggo Mortensen y Kirsten Dunst. SOLO LOS AMANTES Y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6360240w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#mainImage\",\"width\":800,\"height\":509},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\\\/#mainImage\"},\"datePublished\":\"2014-06-12T13:24:16+02:00\",\"dateModified\":\"2014-06-12T13:24:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias","description":"Madrid, 12 jun (EFE).- La cartelera espa\u00f1ola se renueva con t\u00edtulos para todos los p\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en \"S\u00f3lo los amantes sobreviven\", la \u00faltima versi\u00f3n animada de \"Tarz\u00e1n\" y el suspense del \"thriller\" \"Las dos caras de enero\", con Viggo Mortensen y Kirsten Dunst. SOLO LOS AMANTES Y","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#article","name":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias","headline":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w.jpg","width":800,"height":509},"datePublished":"2014-06-12T13:24:16+02:00","dateModified":"2014-06-12T13:24:16+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#listItem","name":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#listItem","position":3,"name":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/","name":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias","description":"Madrid, 12 jun (EFE).- La cartelera espa\u00f1ola se renueva con t\u00edtulos para todos los p\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en \"S\u00f3lo los amantes sobreviven\", la \u00faltima versi\u00f3n animada de \"Tarz\u00e1n\" y el suspense del \"thriller\" \"Las dos caras de enero\", con Viggo Mortensen y Kirsten Dunst. SOLO LOS AMANTES Y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#mainImage","width":800,"height":509},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/#mainImage"},"datePublished":"2014-06-12T13:24:16+02:00","dateModified":"2014-06-12T13:24:16+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias","og:description":"Madrid, 12 jun (EFE).- La cartelera espa\u00f1ola se renueva con t\u00edtulos para todos los p\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en &quot;S\u00f3lo los amantes sobreviven&quot;, la \u00faltima versi\u00f3n animada de &quot;Tarz\u00e1n&quot; y el suspense del &quot;thriller&quot; &quot;Las dos caras de enero&quot;, con Viggo Mortensen y Kirsten Dunst. SOLO LOS AMANTES Y","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w.jpg","og:image:width":800,"og:image:height":509,"article:published_time":"2014-06-12T15:24:16+00:00","article:modified_time":"2014-06-12T15:24:16+00:00","twitter:card":"summary_large_image","twitter:title":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines | El Digital de Asturias","twitter:description":"Madrid, 12 jun (EFE).- La cartelera espa\u00f1ola se renueva con t\u00edtulos para todos los p\u00fablicos que incluyen a los vampiros modernos de Jim Jarmusch en &quot;S\u00f3lo los amantes sobreviven&quot;, la \u00faltima versi\u00f3n animada de &quot;Tarz\u00e1n&quot; y el suspense del &quot;thriller&quot; &quot;Las dos caras de enero&quot;, con Viggo Mortensen y Kirsten Dunst. SOLO LOS AMANTES Y","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6360240w.jpg"},"aioseo_meta_data":{"post_id":"15774","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 13:11:12","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:56:50","updated":"2026-05-16 13:11:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/\" title=\"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines\">Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Estrenos de la semana : Vampiros modernos y un tenso \u00abthriller\u00bb con Viggo Mortensen, en los cines","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/estrenos-de-la-semana-vampiros-modernos-y-un-tenso-thriller-con-viggo-mortensen-en-los-cines\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15774"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15775"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}