{"id":15747,"date":"2014-06-12T13:09:29","date_gmt":"2014-06-12T15:09:29","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15747"},"modified":"2014-06-12T13:09:29","modified_gmt":"2014-06-12T15:09:29","slug":"las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/","title":{"rendered":"Las fotos personales del rey de Marruecos arrasan en Facebook"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15748\" alt=\"6359260w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6359260w-307x300.jpg\" width=\"307\" height=\"300\" \/>Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\u00e1gina de Facebook que muestra im\u00e1genes del monarca en situaciones mucho m\u00e1s espont\u00e1neas que en las de los habituales actos oficiales.<\/p>\n<p>Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \u00c1rabes. Ninguna de las fotos del rey en estos viajes se le escapan a Soufiane ElBahri, de 23 a\u00f1os, natural de Sal\u00e9 (ciudad vecina de Rabat), y administrador de una p\u00e1gina en la red social que cuenta con 1,2 millones de seguidores y m\u00e1s 1,7 millones de amigos en su perfil privado.<\/p>\n<p>La p\u00e1gina se llama simplemente \u00abEl rey de Marruecos Mohammed 6\u00bb (https:\/\/www.facebook.com\/ROI.DU.MAROC.MOHAMED.6), y fue creada por ElBahri en 2008 \u00abcomo un regalo al rey, que Dios le asista\u00bb, y seg\u00fan cont\u00f3 a un diario local (pues se neg\u00f3 a dar una entrevista a Efe) su pasi\u00f3n por el monarca naci\u00f3 a edad muy temprana porque ya desde ni\u00f1o \u00abcada vez que ve\u00eda su imagen abrazaba la pantalla del televisor\u00bb.<\/p>\n<p>El rey ataviado con un gorro, gafas de sol, camiseta y vaqueros, o chaleco y camisa a cuadros o de colores, o con camisa fuera del pantal\u00f3n; esta imagen distendida dista mucho del traje de chaqueta y corbata o de la tradicional chilaba y fez rojo con la que suele aparecer Mohamed VI en los actos p\u00fablicos en Marruecos.<\/p>\n<p>Un monarca todav\u00eda pr\u00edncipe junto a sus compa\u00f1eros de escuela, peregrinando en la Meca, esquiando, tocando la guitarra, jugando al billar o disfrutando de su deporte preferido, el esqu\u00ed acu\u00e1tico, son solo algunas de las fotos recopiladas por ElBahri en varios \u00e1lbumes que recorren la vida del rey desde su infancia hasta la actualidad.<\/p>\n<p>T\u00fanez, finales de mayo o principios de junio. Mohamed VI, de visita en el pa\u00eds, se acerca a un grupo de marroqu\u00edes que lo descubren y le piden una foto. El rey posa con ellos y, tras el primer disparo, sonriente, les pregunta \u00ab\u00bfos ha gustado, o volvemos a posar?\u00bb, seg\u00fan aparece en la p\u00e1gina de ElBahri.<\/p>\n<p>Puede parecer trivial, pero la an\u00e9cdota, inaudita, ilustra la espontaneidad del rey fuera de su corte, y ha merecido 33.357 \u00abme gusta\u00bb en la p\u00e1gina.<\/p>\n<p>La pregunta es: \u00bfC\u00f3mo consigue ElBahri las fotos?.<\/p>\n<p>En una entrevista en marzo concedida al diario local Ajbar al Yaum este joven de ojos azules comentaba que las im\u00e1genes del rey junto a ciudadanos en diferentes partes del mundo se las suministran las mismas personas que aparecen en las im\u00e1genes.<\/p>\n<p>Otro asunto es cuando agrega a la p\u00e1gina las fotos en las que Mohamed VI est\u00e1 solo. Para obtenerlas, cuenta, acude a \u00abfuentes diversas\u00bb, y cuando el periodista le pregunta a qu\u00e9 se refiere, ElBahri responde: \u00abEs un secreto\u00bb.<\/p>\n<p>Sea como fuere, la p\u00e1gina de este estudiante de Derecho causa furor en la red social y, citando sus propias palabras recogidas por la prensa, \u00abmiles de personas han descubierto a trav\u00e9s de la p\u00e1gina otra faceta del rey fuera de los protocolos (&#8230;) Un rey espont\u00e1neo y modesto\u00bb.<\/p>\n<p>Una imagen de espontaneidad y modestia que los medios p\u00fablicos tiene prohibido mostrar, como ha quedado claro esta semana cuando la televisi\u00f3n p\u00fablica 2M tuvo que pedir disculpas tras recibir una llamada de atenci\u00f3n por parte del Ministerio de Protocolo Real despu\u00e9s de mostrar unas im\u00e1genes personales del rey en un inocente paseo en la medina de T\u00fanez.<\/p>\n<p>En un pa\u00eds con una tasa de analfabetismo en torno al 30 %, la televisi\u00f3n es el principal medio de informaci\u00f3n de los marroqu\u00edes y los informativos recogen sin excepci\u00f3n y en un r\u00edgido formato, un recuento lineal de las actividades del monarca. El semanario TelQuel cont\u00f3 en su pasada edici\u00f3n que 32 de 37 minutos de un informativo hab\u00edan sido dedicados a la agenda del rey.<\/p>\n<p>Por el contrario, internet es un medio m\u00e1s vinculado a los j\u00f3venes y en Marruecos existe, hasta el momento, una mayor tolerancia a la hora de hacer circular la informaci\u00f3n, de la que muchas veces se nutren los medios de comunicaci\u00f3n privados que ya han utilizado en varias ocasiones las fotos del rey que circulan por la red.<\/p>\n<p>En un aparente fruto de esta tolerancia con la red, la p\u00e1gina de ElBahri no solo recoge \u00e1lbumes de fotos excepcionales del monarca, sino que los acompa\u00f1a de mensajes pol\u00edticos inequ\u00edvocos.<\/p>\n<p>As\u00ed, da cabida a las manifestaciones de j\u00f3venes promon\u00e1rquicos en las que se levantan carteles contra el movimiento contestatario marroqu\u00ed 20 de Febrero, que naci\u00f3 en 2011 al calor de las protestas en otros pa\u00edses \u00e1rabes.<\/p>\n<p>Entre estos j\u00f3venes promon\u00e1rquicos se distingue al mismo ElBahri con gafas de sol, ondeando una bandera de Marruecos. En otra ocasi\u00f3n aparece, como si de una misi\u00f3n oficial se tratara, visitando a las v\u00edctimas de un atentado terrorista.<\/p>\n<p>No quiere publicidad, rechaza entrevistas y tampoco desea beneficios econ\u00f3micos por su trabajo y sin embargo ElBahri ya se ha convertido en un icono por su pasi\u00f3n mon\u00e1rquica, tanto que un semanario lo ha bautizado como \u00abun adicto a Mohamed VI\u00bb.<\/p>\n<p>Marta Miera<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\u00e1gina de Facebook que muestra im\u00e1genes del monarca en situaciones mucho m\u00e1s espont\u00e1neas que en las de los habituales actos oficiales. Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \u00c1rabes. Ninguna de<\/p>\n","protected":false},"author":1,"featured_media":15748,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15747","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\u00e1gina de Facebook que muestra im\u00e1genes del monarca en situaciones mucho m\u00e1s espont\u00e1neas que en las de los habituales actos oficiales. Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \u00c1rabes. Ninguna de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\u00e1gina de Facebook que muestra im\u00e1genes del monarca en situaciones mucho m\u00e1s espont\u00e1neas que en las de los habituales actos oficiales. Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \u00c1rabes. Ninguna de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6359260w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6359260w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-12T15:09:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-12T15:09:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\u00e1gina de Facebook que muestra im\u00e1genes del monarca en situaciones mucho m\u00e1s espont\u00e1neas que en las de los habituales actos oficiales. Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \u00c1rabes. Ninguna de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6359260w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#article\",\"name\":\"Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias\",\"headline\":\"Las fotos personales del rey de Marruecos arrasan en Facebook\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6359260w.jpg\",\"width\":800,\"height\":780},\"datePublished\":\"2014-06-12T13:09:29+02:00\",\"dateModified\":\"2014-06-12T13:09:29+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#listItem\",\"name\":\"Las fotos personales del rey de Marruecos arrasan en Facebook\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#listItem\",\"position\":3,\"name\":\"Las fotos personales del rey de Marruecos arrasan en Facebook\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/\",\"name\":\"Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias\",\"description\":\"Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\\u00e1gina de Facebook que muestra im\\u00e1genes del monarca en situaciones mucho m\\u00e1s espont\\u00e1neas que en las de los habituales actos oficiales. Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \\u00c1rabes. Ninguna de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6359260w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#mainImage\",\"width\":800,\"height\":780},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\\\/#mainImage\"},\"datePublished\":\"2014-06-12T13:09:29+02:00\",\"dateModified\":\"2014-06-12T13:09:29+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias","description":"Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\u00e1gina de Facebook que muestra im\u00e1genes del monarca en situaciones mucho m\u00e1s espont\u00e1neas que en las de los habituales actos oficiales. Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \u00c1rabes. Ninguna de","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#article","name":"Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias","headline":"Las fotos personales del rey de Marruecos arrasan en Facebook","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6359260w.jpg","width":800,"height":780},"datePublished":"2014-06-12T13:09:29+02:00","dateModified":"2014-06-12T13:09:29+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#listItem","name":"Las fotos personales del rey de Marruecos arrasan en Facebook"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#listItem","position":3,"name":"Las fotos personales del rey de Marruecos arrasan en Facebook","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/","name":"Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias","description":"Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\u00e1gina de Facebook que muestra im\u00e1genes del monarca en situaciones mucho m\u00e1s espont\u00e1neas que en las de los habituales actos oficiales. Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \u00c1rabes. Ninguna de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6359260w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#mainImage","width":800,"height":780},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/#mainImage"},"datePublished":"2014-06-12T13:09:29+02:00","dateModified":"2014-06-12T13:09:29+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias","og:description":"Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\u00e1gina de Facebook que muestra im\u00e1genes del monarca en situaciones mucho m\u00e1s espont\u00e1neas que en las de los habituales actos oficiales. Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \u00c1rabes. Ninguna de","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6359260w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6359260w.jpg","og:image:width":800,"og:image:height":780,"article:published_time":"2014-06-12T15:09:29+00:00","article:modified_time":"2014-06-12T15:09:29+00:00","twitter:card":"summary_large_image","twitter:title":"Las fotos personales del rey de Marruecos arrasan en Facebook | El Digital de Asturias","twitter:description":"Rabat, 12 jun (EFE).- Las fotos personales del rey Mohamed VI de Marruecos en sus viajes al extranjero arrasan en una p\u00e1gina de Facebook que muestra im\u00e1genes del monarca en situaciones mucho m\u00e1s espont\u00e1neas que en las de los habituales actos oficiales. Mohamed VI en Francia, Senegal, Costa de Marfil o Emiratos \u00c1rabes. Ninguna de","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6359260w.jpg"},"aioseo_meta_data":{"post_id":"15747","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 13:07:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:56:50","updated":"2026-05-16 13:07:04"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/\" title=\"Las fotos personales del rey de Marruecos arrasan en Facebook\">Las fotos personales del rey de Marruecos arrasan en Facebook<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Las fotos personales del rey de Marruecos arrasan en Facebook","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-fotos-personales-del-rey-de-marruecos-arrasan-en-facebook\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15747"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15748"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}