{"id":15722,"date":"2014-06-11T23:16:11","date_gmt":"2014-06-12T01:16:11","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15722"},"modified":"2014-06-11T23:16:11","modified_gmt":"2014-06-12T01:16:11","slug":"google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/","title":{"rendered":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15723\" alt=\"6358211w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w-360x253.jpg\" width=\"360\" height=\"253\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w-360x253.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w-650x457.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w-768x540.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w-150x106.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w-450x317.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w-100x70.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w-696x490.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w-597x420.jpg 597w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\u00f3 hoy que el gigante tecnol\u00f3gico estadounidense colaborar\u00e1 con las autoridades europeas para llevar a la pr\u00e1ctica la reciente sentencia sobre el denominado \u00abderecho al olvido\u00bb en internet.<\/p>\n<p>Schmidt argument\u00f3, en un discurso durante la inauguraci\u00f3n de un centro de empresas tecnol\u00f3gicas en Berl\u00edn, que m\u00e1s all\u00e1 de las diferentes posturas sobre la sentencia, lo fundamental era que la Justicia trata de forjar una forma de convivencia com\u00fan en la red y que era importante colaborar.<\/p>\n<p>El Tribunal de Justicia de la Uni\u00f3n Europea respald\u00f3 en mayo el \u00abderecho al olvido\u00bb defendido por Espa\u00f1a al se\u00f1alar que los motores de b\u00fasqueda como Google deben retirar los enlaces a informaciones publicadas en el pasado si se comprueba que perjudican a un ciudadano y no son ya pertinentes.<\/p>\n<p>El presidente ejecutivo de la empresa del buscador m\u00e1s popular de internet anim\u00f3 adem\u00e1s en su intervenci\u00f3n al Gobierno alem\u00e1n y en cierta medida a otros pa\u00edses europeos a mejorar sus infraestructuras digitales, apostar por la educaci\u00f3n y simplificar los procedimientos burocr\u00e1ticos para facilitar la creaci\u00f3n de empresas y la contrataci\u00f3n.<\/p>\n<p>\u00abSe llama fibra. Ponedla\u00bb, se\u00f1al\u00f3, en tono ir\u00f3nico Schmidt en referencia al tipo de cableado que permite una mayor velocidad de navegaci\u00f3n en internet.<\/p>\n<p>Schmidt destac\u00f3 asimismo la evoluci\u00f3n de Berl\u00edn en los \u00faltimos a\u00f1os, de la que destac\u00f3 su renacimiento como \u00abcentro de arte, cultura y tecnolog\u00eda\u00bb tras la reunificaci\u00f3n,<\/p>\n<p>En los \u00faltimos a\u00f1os se est\u00e1n instalando en la capital alemana importantes empresas del mundo digital y est\u00e1n surgiendo multitud de peque\u00f1as iniciativas en materia de software y movilidad.<\/p>\n<p>El centro de empresas tecnol\u00f3gicas inaugurado en Berl\u00edn es una antigua cervecer\u00eda de 16.000 metros cuadrados reconvertida en el coraz\u00f3n de la capital que acoge 22 empresas del sector digital, desde firmas establecidas como la red social Twitter a j\u00f3venes iniciativas de desarrollo de aplicaciones para m\u00f3viles.<\/p>\n<p>El proyecto, denominado Factory, cuenta con el apoyo de Google.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\u00f3 hoy que el gigante tecnol\u00f3gico estadounidense colaborar\u00e1 con las autoridades europeas para llevar a la pr\u00e1ctica la reciente sentencia sobre el denominado \u00abderecho al olvido\u00bb en internet. Schmidt argument\u00f3, en un discurso durante la inauguraci\u00f3n de un centro de empresas tecnol\u00f3gicas en Berl\u00edn, que<\/p>\n","protected":false},"author":1,"featured_media":15723,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[181],"tags":[],"class_list":["post-15722","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internet"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\u00f3 hoy que el gigante tecnol\u00f3gico estadounidense colaborar\u00e1 con las autoridades europeas para llevar a la pr\u00e1ctica la reciente sentencia sobre el denominado &quot;derecho al olvido&quot; en internet. Schmidt argument\u00f3, en un discurso durante la inauguraci\u00f3n de un centro de empresas tecnol\u00f3gicas en Berl\u00edn, que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"internet\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\u00f3 hoy que el gigante tecnol\u00f3gico estadounidense colaborar\u00e1 con las autoridades europeas para llevar a la pr\u00e1ctica la reciente sentencia sobre el denominado &quot;derecho al olvido&quot; en internet. Schmidt argument\u00f3, en un discurso durante la inauguraci\u00f3n de un centro de empresas tecnol\u00f3gicas en Berl\u00edn, que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-12T01:16:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-12T01:16:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\u00f3 hoy que el gigante tecnol\u00f3gico estadounidense colaborar\u00e1 con las autoridades europeas para llevar a la pr\u00e1ctica la reciente sentencia sobre el denominado &quot;derecho al olvido&quot; en internet. Schmidt argument\u00f3, en un discurso durante la inauguraci\u00f3n de un centro de empresas tecnol\u00f3gicas en Berl\u00edn, que\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#article\",\"name\":\"Google asegura que colaborar\\u00e1 con la UE para aplicar el \\u00abderecho al olvido\\u00bb | El Digital de Asturias\",\"headline\":\"Google asegura que colaborar\\u00e1 con la UE para aplicar el \\u00abderecho al olvido\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6358211w.jpg\",\"width\":800,\"height\":563},\"datePublished\":\"2014-06-11T23:16:11+02:00\",\"dateModified\":\"2014-06-11T23:16:11+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#webpage\"},\"articleSection\":\"Internet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/internet\\\/#listItem\",\"name\":\"Internet\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/internet\\\/#listItem\",\"position\":2,\"name\":\"Internet\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/internet\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#listItem\",\"name\":\"Google asegura que colaborar\\u00e1 con la UE para aplicar el \\u00abderecho al olvido\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#listItem\",\"position\":3,\"name\":\"Google asegura que colaborar\\u00e1 con la UE para aplicar el \\u00abderecho al olvido\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/internet\\\/#listItem\",\"name\":\"Internet\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/\",\"name\":\"Google asegura que colaborar\\u00e1 con la UE para aplicar el \\u00abderecho al olvido\\u00bb | El Digital de Asturias\",\"description\":\"Berl\\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\\u00f3 hoy que el gigante tecnol\\u00f3gico estadounidense colaborar\\u00e1 con las autoridades europeas para llevar a la pr\\u00e1ctica la reciente sentencia sobre el denominado \\\"derecho al olvido\\\" en internet. Schmidt argument\\u00f3, en un discurso durante la inauguraci\\u00f3n de un centro de empresas tecnol\\u00f3gicas en Berl\\u00edn, que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6358211w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#mainImage\",\"width\":800,\"height\":563},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\\\/#mainImage\"},\"datePublished\":\"2014-06-11T23:16:11+02:00\",\"dateModified\":\"2014-06-11T23:16:11+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb | El Digital de Asturias","description":"Berl\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\u00f3 hoy que el gigante tecnol\u00f3gico estadounidense colaborar\u00e1 con las autoridades europeas para llevar a la pr\u00e1ctica la reciente sentencia sobre el denominado \"derecho al olvido\" en internet. Schmidt argument\u00f3, en un discurso durante la inauguraci\u00f3n de un centro de empresas tecnol\u00f3gicas en Berl\u00edn, que","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/","robots":"max-image-preview:large","keywords":"internet","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#article","name":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb | El Digital de Asturias","headline":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w.jpg","width":800,"height":563},"datePublished":"2014-06-11T23:16:11+02:00","dateModified":"2014-06-11T23:16:11+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#webpage"},"articleSection":"Internet"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/#listItem","name":"Internet"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/#listItem","position":2,"name":"Internet","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#listItem","name":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#listItem","position":3,"name":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/#listItem","name":"Internet"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/","name":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb | El Digital de Asturias","description":"Berl\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\u00f3 hoy que el gigante tecnol\u00f3gico estadounidense colaborar\u00e1 con las autoridades europeas para llevar a la pr\u00e1ctica la reciente sentencia sobre el denominado \"derecho al olvido\" en internet. Schmidt argument\u00f3, en un discurso durante la inauguraci\u00f3n de un centro de empresas tecnol\u00f3gicas en Berl\u00edn, que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#mainImage","width":800,"height":563},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/#mainImage"},"datePublished":"2014-06-11T23:16:11+02:00","dateModified":"2014-06-11T23:16:11+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb | El Digital de Asturias","og:description":"Berl\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\u00f3 hoy que el gigante tecnol\u00f3gico estadounidense colaborar\u00e1 con las autoridades europeas para llevar a la pr\u00e1ctica la reciente sentencia sobre el denominado &quot;derecho al olvido&quot; en internet. Schmidt argument\u00f3, en un discurso durante la inauguraci\u00f3n de un centro de empresas tecnol\u00f3gicas en Berl\u00edn, que","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w.jpg","og:image:width":800,"og:image:height":563,"article:published_time":"2014-06-12T01:16:11+00:00","article:modified_time":"2014-06-12T01:16:11+00:00","twitter:card":"summary_large_image","twitter:title":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb | El Digital de Asturias","twitter:description":"Berl\u00edn, 11 jun (EFE).- El presidente de Google, Eric Schmidt, afirm\u00f3 hoy que el gigante tecnol\u00f3gico estadounidense colaborar\u00e1 con las autoridades europeas para llevar a la pr\u00e1ctica la reciente sentencia sobre el denominado &quot;derecho al olvido&quot; en internet. Schmidt argument\u00f3, en un discurso durante la inauguraci\u00f3n de un centro de empresas tecnol\u00f3gicas en Berl\u00edn, que","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6358211w.jpg"},"aioseo_meta_data":{"post_id":"15722","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 13:05:00","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:56:50","updated":"2026-05-16 13:05:00"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/\" title=\"Internet\">Internet<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/\" title=\"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb\">Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Internet","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/"},{"label":"Google asegura que colaborar\u00e1 con la UE para aplicar el \u00abderecho al olvido\u00bb","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/google-asegura-que-colaborara-con-la-ue-para-aplicar-el-derecho-al-olvido\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15722"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15723"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}