{"id":15710,"date":"2014-06-11T20:28:13","date_gmt":"2014-06-11T22:28:13","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15710"},"modified":"2014-06-11T20:28:13","modified_gmt":"2014-06-11T22:28:13","slug":"la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/","title":{"rendered":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15711\" alt=\"6357579w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6357579w-354x300.jpg\" width=\"354\" height=\"300\" \/>Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\u00f3n, MIFA, ha puesto en evidencia este a\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales.<\/p>\n<p>\u00abHay una gran pujanza de Am\u00e9rica Latina, que desarrolla su participaci\u00f3n, y de Espa\u00f1a, con muchas empresas bajo el paraguas del ICEX y de Catalan Films&amp;TV\u00bb, asegur\u00f3 hoy a EFE el responsable del MIFA, Micka\u00ebl Marin.<\/p>\n<p>En el caso espa\u00f1ol se constata \u00abuna recuperaci\u00f3n\u00bb, lo que hace suponer \u00abque los peores a\u00f1os han quedado atr\u00e1s\u00bb, explic\u00f3 Marin, quien adelant\u00f3 que en la pr\u00f3xima edici\u00f3n del Festival de Cine de Animaci\u00f3n de Annecy, en el que se enmarca este mercado, Espa\u00f1a ser\u00e1 el pa\u00eds homenajeado.<\/p>\n<p>Este a\u00f1o, aparte de la coproducci\u00f3n \u00abCuentos de viejos\u00bb, que compite como telefilme, la pel\u00edcula \u00abJustin y la espada del valor\u00bb, dirigida por Manuel Sicilia, con Antonio Banderas como productor, es la \u00fanica representante espa\u00f1ola en la secci\u00f3n oficial de largometrajes, en la que se integra fuera de competici\u00f3n.<\/p>\n<p>Se trata de la \u00faltima gran producci\u00f3n de la industria espa\u00f1ola, desarrollada en los a\u00f1os de la crisis, y que ha sido vendida a unos 140 territorios, de los cuales se ha estrenado ya en cerca de 90.<\/p>\n<p>\u00abEstamos muy contentos porque Annecy se ha transformado en el centro de la animaci\u00f3n mundial\u00bb, explic\u00f3 Sicilia, quien mostr\u00f3 su satisfacci\u00f3n por poder presentar su pel\u00edcula ante un p\u00fablico \u00abmuy exigente\u00bb.<\/p>\n<p>En este momento, su compa\u00f1\u00eda, Kandor Graphics, con sede en Granada, est\u00e1 desarrollando tres proyectos que prev\u00e9 presentar a \u00absocios clave\u00bb durante estos d\u00edas en los que Annecy re\u00fane a los principales representantes de la industria mundial de la animaci\u00f3n.<\/p>\n<p>El Instituto Espa\u00f1ol de Comercio Exterior (ICEX) acude por primera vez a esta feria con un pabell\u00f3n informativo denominado \u00abAnimation from Spain\u00bb, para responder a la demanda de las empresas.<\/p>\n<p>Catalan Films&amp;TV, por su parte, renueva su compromiso con el MIFA con \u00abmuchas m\u00e1s productoras que en a\u00f1os anteriores\u00bb, explic\u00f3 la t\u00e9cnica de promoci\u00f3n internacional Sandra Reina, quien precis\u00f3 que este a\u00f1o amparan a m\u00e1s de treinta compa\u00f1\u00edas acreditadas, frente a las veinte de 2013.<\/p>\n<p>\u00abVemos que est\u00e1 empezando a resurgir la animaci\u00f3n\u00bb, puesto que \u00abla crisis hizo bastante da\u00f1o al sector\u00bb, afirm\u00f3 la representante de Catalan Films&amp;TV en el MIFA.<\/p>\n<p>Entre las empresas presentes se encuentra Edeb\u00e9, que tiene previsto presentar ma\u00f1ana ante la industria su serie de televisi\u00f3n \u00abYo, Elvis Riboldi\u00bb, para avanzar en su objetivo de conseguir los cuatro millones de euros que requiere este proyecto.<\/p>\n<p>\u00abDespu\u00e9s de los cinco a\u00f1os de crisis que han pasado ya, las empresas que no han ca\u00eddo por el camino no van a caer\u00bb, declar\u00f3 Iv\u00e1n Agenjo, productor ejecutivo de la serie, para quien las compa\u00f1\u00edas que han superado esta etapa \u00abhan salido reforzadas\u00bb.<\/p>\n<p>Este repunte parece estar m\u00e1s vinculado, no obstante, a las producciones de televisi\u00f3n que de cine, puesto que no se hac\u00eda gala de esta efusividad en una de las \u00faltimas citas de la animaci\u00f3n, el Cartoon Movie del pasado marzo.<\/p>\n<p>M\u00e9xico, Colombia, Argentina, Chile y Brasil son los representantes de Latinoam\u00e9rica en un mercado que ha dedicado una atenci\u00f3n especial a esta regi\u00f3n con un \u00abTerritory Focus\u00bb, centrado en Brasil y Chile, en el que podr\u00e1n presentar su talento y capacidad.<\/p>\n<p>RTVC Se\u00f1al Colombia tambi\u00e9n se dirigir\u00e1 al sector de la animaci\u00f3n. \u00abEl objetivo es contar lo que estamos haciendo y seguir consolid\u00e1ndonos en el mapa\u00bb, asegur\u00f3 Claudia Rodr\u00edguez Valencia, directora de asuntos internacionales de esta televisi\u00f3n que lleva dos a\u00f1os acudiendo al MIFA.<\/p>\n<p>En los \u00faltimos tres a\u00f1os, RTVC ha invertido un mill\u00f3n y medio de euros en la coproducci\u00f3n de una docena de series, un impulso que discurre paralelo a su apuesta por la internacionalizaci\u00f3n.<\/p>\n<p>\u00abLa animaci\u00f3n est\u00e1 creciendo much\u00edsimo en M\u00e9xico\u00bb, donde actualmente se est\u00e1n produciendo una decena de largometrajes, afirm\u00f3 Jos\u00e9 I\u00f1esta, representante de Pixelatl, plataforma que contribuye a la promoci\u00f3n de las empresas mexicanas en el MIFA.<\/p>\n<p>M\u00e1s all\u00e1 de lo que representa Iberoam\u00e9rica, el mercado de animaci\u00f3n de Annecy espera superar los 2.400 profesionales, lo que supondr\u00eda \u00abun r\u00e9cord\u00bb para este sector al alza, explic\u00f3 Marin, responsable de este evento que finaliza el pr\u00f3ximo viernes.<\/p>\n<p>&nbsp;<\/p>\n<p>Mercedes \u00c1lvarez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\u00f3n, MIFA, ha puesto en evidencia este a\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales. \u00abHay una gran pujanza de Am\u00e9rica Latina, que desarrolla su participaci\u00f3n, y de<\/p>\n","protected":false},"author":1,"featured_media":15711,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15710","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\u00f3n, MIFA, ha puesto en evidencia este a\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales. &quot;Hay una gran pujanza de Am\u00e9rica Latina, que desarrolla su participaci\u00f3n, y de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\u00f3n, MIFA, ha puesto en evidencia este a\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales. &quot;Hay una gran pujanza de Am\u00e9rica Latina, que desarrolla su participaci\u00f3n, y de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6357579w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6357579w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-11T22:28:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-11T22:28:13+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\u00f3n, MIFA, ha puesto en evidencia este a\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales. &quot;Hay una gran pujanza de Am\u00e9rica Latina, que desarrolla su participaci\u00f3n, y de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6357579w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#article\",\"name\":\"La animaci\\u00f3n espa\\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias\",\"headline\":\"La animaci\\u00f3n espa\\u00f1ola repunta tras la crisis y la latinoamericana despunta\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6357579w.jpg\",\"width\":800,\"height\":677},\"datePublished\":\"2014-06-11T20:28:13+02:00\",\"dateModified\":\"2014-06-11T20:28:13+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#listItem\",\"name\":\"La animaci\\u00f3n espa\\u00f1ola repunta tras la crisis y la latinoamericana despunta\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#listItem\",\"position\":3,\"name\":\"La animaci\\u00f3n espa\\u00f1ola repunta tras la crisis y la latinoamericana despunta\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/\",\"name\":\"La animaci\\u00f3n espa\\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias\",\"description\":\"Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\\u00f3n, MIFA, ha puesto en evidencia este a\\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales. \\\"Hay una gran pujanza de Am\\u00e9rica Latina, que desarrolla su participaci\\u00f3n, y de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6357579w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#mainImage\",\"width\":800,\"height\":677},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\\\/#mainImage\"},\"datePublished\":\"2014-06-11T20:28:13+02:00\",\"dateModified\":\"2014-06-11T20:28:13+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias","description":"Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\u00f3n, MIFA, ha puesto en evidencia este a\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales. \"Hay una gran pujanza de Am\u00e9rica Latina, que desarrolla su participaci\u00f3n, y de","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#article","name":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias","headline":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6357579w.jpg","width":800,"height":677},"datePublished":"2014-06-11T20:28:13+02:00","dateModified":"2014-06-11T20:28:13+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#listItem","name":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#listItem","position":3,"name":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/","name":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias","description":"Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\u00f3n, MIFA, ha puesto en evidencia este a\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales. \"Hay una gran pujanza de Am\u00e9rica Latina, que desarrolla su participaci\u00f3n, y de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6357579w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#mainImage","width":800,"height":677},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/#mainImage"},"datePublished":"2014-06-11T20:28:13+02:00","dateModified":"2014-06-11T20:28:13+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias","og:description":"Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\u00f3n, MIFA, ha puesto en evidencia este a\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales. &quot;Hay una gran pujanza de Am\u00e9rica Latina, que desarrolla su participaci\u00f3n, y de","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6357579w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6357579w.jpg","og:image:width":800,"og:image:height":677,"article:published_time":"2014-06-11T22:28:13+00:00","article:modified_time":"2014-06-11T22:28:13+00:00","twitter:card":"summary_large_image","twitter:title":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta | El Digital de Asturias","twitter:description":"Annecy (Francia), 11 jun (EFE).- El principal mercado de la animaci\u00f3n, MIFA, ha puesto en evidencia este a\u00f1o el despunte de la industria latinoamericana y la vuelta al ruedo de la espa\u00f1ola, que buscan en esa cita visibilidad y nuevas oportunidades comerciales. &quot;Hay una gran pujanza de Am\u00e9rica Latina, que desarrolla su participaci\u00f3n, y de","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6357579w.jpg"},"aioseo_meta_data":{"post_id":"15710","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 13:03:11","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:57:49","updated":"2026-05-16 13:03:11"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/\" title=\"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta\">La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"La animaci\u00f3n espa\u00f1ola repunta tras la crisis y la latinoamericana despunta","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-animacion-espanola-repunta-tras-la-crisis-y-la-latinoamericana-despunta\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15710"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15711"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}