{"id":15686,"date":"2014-06-11T20:03:39","date_gmt":"2014-06-11T22:03:39","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15686"},"modified":"2014-06-11T20:03:39","modified_gmt":"2014-06-11T22:03:39","slug":"rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/","title":{"rendered":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15687\" alt=\"6356459w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6356459w-196x300.jpg\" width=\"196\" height=\"300\" \/>Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\u00e9same a la familia de Rafael Fr\u00fchbeck de Burgos, fallecido hoy a los 80 a\u00f1os, en el que alaba el \u00abextraordinario talento\u00bb del director espa\u00f1ol y asegura que era el de \u00abmayor proyecci\u00f3n internacional\u00bb.<\/p>\n<p>El maestro, que anunci\u00f3 su retirada el pasado d\u00eda 4, llevaba hospitalizado en una cl\u00ednica pamplonica desde el 13 de abril a causa de un proceso canceroso.<\/p>\n<p>En su telegrama, Rajoy traslada el p\u00e9same del Gobierno por el fallecimiento del \u00abilustre\u00bb director, cuyo trabajo con las \u00abprincipales\u00bb orquestas del mundo en los escenarios \u00abm\u00e1s prestigiosos\u00bb ha dejado \u00abla huella de su extraordinaria formaci\u00f3n, talento y experiencia\u00bb.<\/p>\n<p>\u00abSu prestigio sirvi\u00f3 a la difusi\u00f3n de la m\u00fasica y de los artistas espa\u00f1oles, y hacen de \u00e9l una referencia inexcusable de la cultura espa\u00f1ola\u00bb, subraya Rajoy.<\/p>\n<p>La capilla ardiente quedar\u00e1 instalada en el tanatorio de la Cl\u00ednica Universitaria de Navarra, donde estaba ingresado desde el 13 de abril, en la que los restos de del director ser\u00e1n velados \u00aben la m\u00e1s estricta intimidad\u00bb, seg\u00fan expreso deseo de la familia.<\/p>\n<p>Fr\u00fchbeck de Burgos ser\u00e1 enterrado ma\u00f1ana, con toda probabilidad en el pante\u00f3n familiar del Cementerio de Burgos, junto a sus padres, en una ceremonia \u00edntima, tal y como \u00e9l deseaba.<\/p>\n<p>Fr\u00fchbeck de Burgos, nacido como Rafael Fr\u00fchbeck Fr\u00fchbeck en la ciudad de la que tom\u00f3 el apellido el 15 de septiembre de 1933, est\u00e1 considerado como el director de orquesta espa\u00f1ol con mayor prestigio internacional desde Ata\u00falfo Argenta, y en la actualidad era titular de la Orquesta Sinf\u00f3nica de Dinamarca y director em\u00e9rito de la Orquesta Nacional de Espa\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\u00e9same a la familia de Rafael Fr\u00fchbeck de Burgos, fallecido hoy a los 80 a\u00f1os, en el que alaba el \u00abextraordinario talento\u00bb del director espa\u00f1ol y asegura que era el de \u00abmayor proyecci\u00f3n internacional\u00bb. El maestro, que anunci\u00f3 su retirada<\/p>\n","protected":false},"author":1,"featured_media":15687,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15686","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\u00e9same a la familia de Rafael Fr\u00fchbeck de Burgos, fallecido hoy a los 80 a\u00f1os, en el que alaba el &quot;extraordinario talento&quot; del director espa\u00f1ol y asegura que era el de &quot;mayor proyecci\u00f3n internacional&quot;. El maestro, que anunci\u00f3 su retirada\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\u00e9same a la familia de Rafael Fr\u00fchbeck de Burgos, fallecido hoy a los 80 a\u00f1os, en el que alaba el &quot;extraordinario talento&quot; del director espa\u00f1ol y asegura que era el de &quot;mayor proyecci\u00f3n internacional&quot;. El maestro, que anunci\u00f3 su retirada\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6356459w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6356459w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-11T22:03:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-11T22:03:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\u00e9same a la familia de Rafael Fr\u00fchbeck de Burgos, fallecido hoy a los 80 a\u00f1os, en el que alaba el &quot;extraordinario talento&quot; del director espa\u00f1ol y asegura que era el de &quot;mayor proyecci\u00f3n internacional&quot;. El maestro, que anunci\u00f3 su retirada\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6356459w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#article\",\"name\":\"Rajoy alaba el \\u00abextraordinario talento\\u00bb de Fr\\u00fchbeck de Burgos en su p\\u00e9same | El Digital de Asturias\",\"headline\":\"Rajoy alaba el \\u00abextraordinario talento\\u00bb de Fr\\u00fchbeck de Burgos en su p\\u00e9same\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6356459w.jpg\",\"width\":700,\"height\":1068},\"datePublished\":\"2014-06-11T20:03:39+02:00\",\"dateModified\":\"2014-06-11T20:03:39+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#listItem\",\"name\":\"Rajoy alaba el \\u00abextraordinario talento\\u00bb de Fr\\u00fchbeck de Burgos en su p\\u00e9same\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#listItem\",\"position\":3,\"name\":\"Rajoy alaba el \\u00abextraordinario talento\\u00bb de Fr\\u00fchbeck de Burgos en su p\\u00e9same\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/\",\"name\":\"Rajoy alaba el \\u00abextraordinario talento\\u00bb de Fr\\u00fchbeck de Burgos en su p\\u00e9same | El Digital de Asturias\",\"description\":\"Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\\u00e9same a la familia de Rafael Fr\\u00fchbeck de Burgos, fallecido hoy a los 80 a\\u00f1os, en el que alaba el \\\"extraordinario talento\\\" del director espa\\u00f1ol y asegura que era el de \\\"mayor proyecci\\u00f3n internacional\\\". El maestro, que anunci\\u00f3 su retirada\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6356459w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#mainImage\",\"width\":700,\"height\":1068},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\\\/#mainImage\"},\"datePublished\":\"2014-06-11T20:03:39+02:00\",\"dateModified\":\"2014-06-11T20:03:39+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same | El Digital de Asturias","description":"Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\u00e9same a la familia de Rafael Fr\u00fchbeck de Burgos, fallecido hoy a los 80 a\u00f1os, en el que alaba el \"extraordinario talento\" del director espa\u00f1ol y asegura que era el de \"mayor proyecci\u00f3n internacional\". El maestro, que anunci\u00f3 su retirada","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#article","name":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same | El Digital de Asturias","headline":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6356459w.jpg","width":700,"height":1068},"datePublished":"2014-06-11T20:03:39+02:00","dateModified":"2014-06-11T20:03:39+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#listItem","name":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#listItem","position":3,"name":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/","name":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same | El Digital de Asturias","description":"Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\u00e9same a la familia de Rafael Fr\u00fchbeck de Burgos, fallecido hoy a los 80 a\u00f1os, en el que alaba el \"extraordinario talento\" del director espa\u00f1ol y asegura que era el de \"mayor proyecci\u00f3n internacional\". El maestro, que anunci\u00f3 su retirada","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6356459w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#mainImage","width":700,"height":1068},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/#mainImage"},"datePublished":"2014-06-11T20:03:39+02:00","dateModified":"2014-06-11T20:03:39+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same | El Digital de Asturias","og:description":"Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\u00e9same a la familia de Rafael Fr\u00fchbeck de Burgos, fallecido hoy a los 80 a\u00f1os, en el que alaba el &quot;extraordinario talento&quot; del director espa\u00f1ol y asegura que era el de &quot;mayor proyecci\u00f3n internacional&quot;. El maestro, que anunci\u00f3 su retirada","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6356459w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6356459w.jpg","og:image:width":700,"og:image:height":1068,"article:published_time":"2014-06-11T22:03:39+00:00","article:modified_time":"2014-06-11T22:03:39+00:00","twitter:card":"summary_large_image","twitter:title":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same | El Digital de Asturias","twitter:description":"Madrid, 11 jun (EFE).- El presidente del Gobierno, Mariano Rajoy, ha enviado un telegrama de p\u00e9same a la familia de Rafael Fr\u00fchbeck de Burgos, fallecido hoy a los 80 a\u00f1os, en el que alaba el &quot;extraordinario talento&quot; del director espa\u00f1ol y asegura que era el de &quot;mayor proyecci\u00f3n internacional&quot;. El maestro, que anunci\u00f3 su retirada","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6356459w.jpg"},"aioseo_meta_data":{"post_id":"15686","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 12:58:12","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:57:49","updated":"2026-05-16 12:58:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/\" title=\"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same\">Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Rajoy alaba el \u00abextraordinario talento\u00bb de Fr\u00fchbeck de Burgos en su p\u00e9same","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/rajoy-alaba-el-extraordinario-talento-de-fruhbeck-de-burgos-en-su-pesame\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15686"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15687"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}