{"id":15550,"date":"2014-06-10T20:18:15","date_gmt":"2014-06-10T22:18:15","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15550"},"modified":"2014-06-10T20:18:15","modified_gmt":"2014-06-10T22:18:15","slug":"chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/","title":{"rendered":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15551\" alt=\"6352605w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6352605w-182x300.jpg\" width=\"182\" height=\"300\" \/>C\u00e1ceres, 9 jun (EFE).- El disc jockey, m\u00fasico y productor de m\u00fasica electr\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\u00f3n de Horteralia, que se celebrar\u00e1 el 13 de septiembre en la plaza de toros de C\u00e1ceres.<\/p>\n<p>El particular carnaval de C\u00e1ceres, que organiza la asociaci\u00f3n cultural Avuelapluma, contar\u00e1 con la presencia de Chimo Bayo, \u00abreferente inequ\u00edvoco\u00bb de la \u00abMovida Valenciana\u00bb y figura clave del techno espa\u00f1ol, con temas como \u00abAs\u00ed me gusta a m\u00ed\u00bb y \u00abBombas\u00bb.<\/p>\n<p>La cantante Rebeca, popular en los a\u00f1os noventa por su sencillo \u00abDuro de pelar\u00bb y su paso por programas de telerealidad, tambi\u00e9n empu\u00f1ar\u00e1 el micr\u00f3fono en el escenario de Horteralia 5.<\/p>\n<p>La artista acaba de lanzar una versi\u00f3n de \u00abGloria\u00bb, el conocido cl\u00e1sico de Umberto Tozzi.<\/p>\n<p>Por su parte, Leticia Sabater, \u00abque fue una figura clave de la televisi\u00f3n infantil de los noventa\u00bb, explican desde la organizaci\u00f3n del festival, ser\u00e1 la encargada de dar el preg\u00f3n de la fiesta, tarea que el a\u00f1o pasado recay\u00f3 en Ca\u00f1ita Brava.<\/p>\n<p>El cartel de este a\u00f1o lo completan Starkytch Pinchadiscos, la Orquesta Punto 3, el tradicional DJ Hortera, el Tributo a Mecano y la actuaci\u00f3n de DJ Privan De Camp<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e1ceres, 9 jun (EFE).- El disc jockey, m\u00fasico y productor de m\u00fasica electr\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\u00f3n de Horteralia, que se celebrar\u00e1 el 13 de septiembre en la plaza de toros de C\u00e1ceres. El particular carnaval de C\u00e1ceres, que organiza<\/p>\n","protected":false},"author":1,"featured_media":15551,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15550","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"C\u00e1ceres, 9 jun (EFE).- El disc jockey, m\u00fasico y productor de m\u00fasica electr\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\u00f3n de Horteralia, que se celebrar\u00e1 el 13 de septiembre en la plaza de toros de C\u00e1ceres. El particular carnaval de C\u00e1ceres, que organiza\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"C\u00e1ceres, 9 jun (EFE).- El disc jockey, m\u00fasico y productor de m\u00fasica electr\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\u00f3n de Horteralia, que se celebrar\u00e1 el 13 de septiembre en la plaza de toros de C\u00e1ceres. El particular carnaval de C\u00e1ceres, que organiza\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6352605w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6352605w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1149\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-10T22:18:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-10T22:18:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"C\u00e1ceres, 9 jun (EFE).- El disc jockey, m\u00fasico y productor de m\u00fasica electr\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\u00f3n de Horteralia, que se celebrar\u00e1 el 13 de septiembre en la plaza de toros de C\u00e1ceres. El particular carnaval de C\u00e1ceres, que organiza\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6352605w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#article\",\"name\":\"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias\",\"headline\":\"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6352605w.jpg\",\"width\":700,\"height\":1149},\"datePublished\":\"2014-06-10T20:18:15+02:00\",\"dateModified\":\"2014-06-10T20:18:15+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#listItem\",\"name\":\"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#listItem\",\"position\":3,\"name\":\"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/\",\"name\":\"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias\",\"description\":\"C\\u00e1ceres, 9 jun (EFE).- El disc jockey, m\\u00fasico y productor de m\\u00fasica electr\\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\\u00f3n de Horteralia, que se celebrar\\u00e1 el 13 de septiembre en la plaza de toros de C\\u00e1ceres. El particular carnaval de C\\u00e1ceres, que organiza\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6352605w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#mainImage\",\"width\":700,\"height\":1149},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\\\/#mainImage\"},\"datePublished\":\"2014-06-10T20:18:15+02:00\",\"dateModified\":\"2014-06-10T20:18:15+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias","description":"C\u00e1ceres, 9 jun (EFE).- El disc jockey, m\u00fasico y productor de m\u00fasica electr\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\u00f3n de Horteralia, que se celebrar\u00e1 el 13 de septiembre en la plaza de toros de C\u00e1ceres. El particular carnaval de C\u00e1ceres, que organiza","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#article","name":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias","headline":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6352605w.jpg","width":700,"height":1149},"datePublished":"2014-06-10T20:18:15+02:00","dateModified":"2014-06-10T20:18:15+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#listItem","name":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#listItem","position":3,"name":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/","name":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias","description":"C\u00e1ceres, 9 jun (EFE).- El disc jockey, m\u00fasico y productor de m\u00fasica electr\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\u00f3n de Horteralia, que se celebrar\u00e1 el 13 de septiembre en la plaza de toros de C\u00e1ceres. El particular carnaval de C\u00e1ceres, que organiza","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6352605w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#mainImage","width":700,"height":1149},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/#mainImage"},"datePublished":"2014-06-10T20:18:15+02:00","dateModified":"2014-06-10T20:18:15+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias","og:description":"C\u00e1ceres, 9 jun (EFE).- El disc jockey, m\u00fasico y productor de m\u00fasica electr\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\u00f3n de Horteralia, que se celebrar\u00e1 el 13 de septiembre en la plaza de toros de C\u00e1ceres. El particular carnaval de C\u00e1ceres, que organiza","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6352605w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6352605w.jpg","og:image:width":700,"og:image:height":1149,"article:published_time":"2014-06-10T22:18:15+00:00","article:modified_time":"2014-06-10T22:18:15+00:00","twitter:card":"summary_large_image","twitter:title":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia | El Digital de Asturias","twitter:description":"C\u00e1ceres, 9 jun (EFE).- El disc jockey, m\u00fasico y productor de m\u00fasica electr\u00f3nica Chimo Bayo, la cantante Rebeca y la expresentadora de televisi\u00f3n Leticia Sabater encabezan el cartel de la quinta edici\u00f3n de Horteralia, que se celebrar\u00e1 el 13 de septiembre en la plaza de toros de C\u00e1ceres. El particular carnaval de C\u00e1ceres, que organiza","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6352605w.jpg"},"aioseo_meta_data":{"post_id":"15550","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 12:39:20","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:00:47","updated":"2026-05-16 12:39:20"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/\" title=\"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia\">Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Chimo Bayo, Rebeca y Leticia Sabater encabezan el cartel de Horteralia","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/chimo-bayo-rebeca-y-leticia-sabater-encabezan-el-cartel-de-horteralia\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15550"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15551"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}