{"id":15385,"date":"2014-06-09T10:14:01","date_gmt":"2014-06-09T12:14:01","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15385"},"modified":"2014-06-09T10:14:01","modified_gmt":"2014-06-09T12:14:01","slug":"una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/","title":{"rendered":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15386\" alt=\"6345618w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6345618w-360x262.jpg\" width=\"360\" height=\"262\" \/>Shangh\u00e1i (China), 9 jun (EFE).- Una quincena de pel\u00edculas de 11 pa\u00edses, ninguna de ellas en espa\u00f1ol, competir\u00e1n este a\u00f1o en la decimos\u00e9ptima edici\u00f3n del Festival Internacional de Cine de Shangh\u00e1i (SIFF), el certamen m\u00e1s joven del mundo de clase A, que se celebrar\u00e1 en la capital econ\u00f3mica de China entre el 14 y el 22 de junio.<\/p>\n<p>A esas proyecciones se sumar\u00e1n las de otras 300 pel\u00edculas que se programar\u00e1n en 35 cines de toda la ciudad en el marco del festival, anunci\u00f3 hoy la organizaci\u00f3n mediante un comunicado.<\/p>\n<p>El festival, que contar\u00e1 con la presencia de estrellas internacionales como Nicole Kidman, Natalie Portman, Hugh Grant, Hayden Christensen o Gong Li, quien presidir\u00e1 el jurado de este a\u00f1o, entregar\u00e1 el d\u00eda 22 sus ocho premios \u00abJin Jue\u00bb, una estatuilla en forma de una antigua copa tradicional china (\u00abjue\u00bb) de oro (\u00abjin\u00bb).<\/p>\n<p>Este a\u00f1o participan en competici\u00f3n por los \u00abJin Jue\u00bb 15 pel\u00edculas, entre ellas \u00abCanopy\u00bb (Aaron Wilson, Australia), \u00abBarf\u00bb (Mehdi Rahmani, Ir\u00e1n), \u00abAnt Story\u00bb (Mostofa Sarwar Farooki, Bangladesh), \u00abMikra Anglia\u00bb (Pantelis Voulgaris, Grecia) y \u00abGozdovi so se vedno zeleni\u00bb (de Marko Nabersnik, Eslovenia\/Alemania).<\/p>\n<p>Adem\u00e1s compiten \u00abTattoo\u00bb (Zhang Meng, China), \u00abThe Last Executioner\u00bb (Tom Waller, Tailandia), \u00abEliza Graves\u00bb (Brad Anderson, EEUU), \u00abDiplomatie\u00bb (Volker Schl\u00f6ndorff, Francia\/Alemania), \u00abBegin Again\u00bb (John Carney, EEUU), \u00abElle l&#8217;adore\u00bb (Jeanne Herry, Francia) y \u00abPyojeok\u00bb (Yoon Hong-Seung, Corea del Sur).<\/p>\n<p>Completan la lista \u00abPredestination\u00bb (Michael y Peter Spierig, Australia\u00bb, \u00abThe Sacred Arrow\u00bb (del tibetano Pema Tseden, China), y \u00abMaiko wa Lady\u00bb (Masayuki Suo, Jap\u00f3n).<\/p>\n<p>Si en 2012 el cine hispanohablante tuvo su mayor representaci\u00f3n y sus mejores resultados en Shangh\u00e1i desde el inicio del festival (en 1994), con dos pel\u00edculas iberoamericanas en competici\u00f3n y premios para ambas, en 2013 no hubo ninguna cinta en espa\u00f1ol entre las 12 que compitieron, al igual que ocurre ahora entre las 15 de este a\u00f1o.<\/p>\n<p>El jurado de este a\u00f1o estar\u00e1 encabezado por la actriz china Gong Li, la antigua musa de Zhang Yimou, el director chino m\u00e1s reconocido internacionalmente, y le acompa\u00f1ar\u00e1n la directora brit\u00e1nica Sally Potter, el director dan\u00e9s Lone Scherfig, el realizador surcoreano Im Sangsoo y el guionista japon\u00e9s Shunji Iwai.<\/p>\n<p>El grupo del jurado se completar\u00e1 este a\u00f1o con el director chino Liu Jie y el actor iran\u00ed Payman Maadi.<\/p>\n<p>En los \u00faltimos a\u00f1os, el SIFF tuvo como presidentes del jurado a los directores Luc Besson, Danny Boyle, Jean-Jacques Annaud, Wong Kar-Wai, John Woo, Tom Hooper, Barry Levinson y Chen Kaige, y en la \u00faltima d\u00e9cada lleg\u00f3 a contar con miembros espa\u00f1oles como Fernando Trueba, Pen\u00e9lope Cruz y Manuel Guti\u00e9rrez Arag\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shangh\u00e1i (China), 9 jun (EFE).- Una quincena de pel\u00edculas de 11 pa\u00edses, ninguna de ellas en espa\u00f1ol, competir\u00e1n este a\u00f1o en la decimos\u00e9ptima edici\u00f3n del Festival Internacional de Cine de Shangh\u00e1i (SIFF), el certamen m\u00e1s joven del mundo de clase A, que se celebrar\u00e1 en la capital econ\u00f3mica de China entre el 14 y el<\/p>\n","protected":false},"author":1,"featured_media":15386,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15385","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Shangh\u00e1i (China), 9 jun (EFE).- Una quincena de pel\u00edculas de 11 pa\u00edses, ninguna de ellas en espa\u00f1ol, competir\u00e1n este a\u00f1o en la decimos\u00e9ptima edici\u00f3n del Festival Internacional de Cine de Shangh\u00e1i (SIFF), el certamen m\u00e1s joven del mundo de clase A, que se celebrar\u00e1 en la capital econ\u00f3mica de China entre el 14 y el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Shangh\u00e1i (China), 9 jun (EFE).- Una quincena de pel\u00edculas de 11 pa\u00edses, ninguna de ellas en espa\u00f1ol, competir\u00e1n este a\u00f1o en la decimos\u00e9ptima edici\u00f3n del Festival Internacional de Cine de Shangh\u00e1i (SIFF), el certamen m\u00e1s joven del mundo de clase A, que se celebrar\u00e1 en la capital econ\u00f3mica de China entre el 14 y el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6345618w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6345618w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"584\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-09T12:14:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-09T12:14:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Shangh\u00e1i (China), 9 jun (EFE).- Una quincena de pel\u00edculas de 11 pa\u00edses, ninguna de ellas en espa\u00f1ol, competir\u00e1n este a\u00f1o en la decimos\u00e9ptima edici\u00f3n del Festival Internacional de Cine de Shangh\u00e1i (SIFF), el certamen m\u00e1s joven del mundo de clase A, que se celebrar\u00e1 en la capital econ\u00f3mica de China entre el 14 y el\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6345618w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#article\",\"name\":\"Una quincena de pel\\u00edculas competir\\u00e1n este a\\u00f1o en Festival de Cine de Shangh\\u00e1i | El Digital de Asturias\",\"headline\":\"Una quincena de pel\\u00edculas competir\\u00e1n este a\\u00f1o en Festival de Cine de Shangh\\u00e1i\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6345618w.jpg\",\"width\":800,\"height\":584},\"datePublished\":\"2014-06-09T10:14:01+02:00\",\"dateModified\":\"2014-06-09T10:14:01+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#listItem\",\"name\":\"Una quincena de pel\\u00edculas competir\\u00e1n este a\\u00f1o en Festival de Cine de Shangh\\u00e1i\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#listItem\",\"position\":3,\"name\":\"Una quincena de pel\\u00edculas competir\\u00e1n este a\\u00f1o en Festival de Cine de Shangh\\u00e1i\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/\",\"name\":\"Una quincena de pel\\u00edculas competir\\u00e1n este a\\u00f1o en Festival de Cine de Shangh\\u00e1i | El Digital de Asturias\",\"description\":\"Shangh\\u00e1i (China), 9 jun (EFE).- Una quincena de pel\\u00edculas de 11 pa\\u00edses, ninguna de ellas en espa\\u00f1ol, competir\\u00e1n este a\\u00f1o en la decimos\\u00e9ptima edici\\u00f3n del Festival Internacional de Cine de Shangh\\u00e1i (SIFF), el certamen m\\u00e1s joven del mundo de clase A, que se celebrar\\u00e1 en la capital econ\\u00f3mica de China entre el 14 y el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6345618w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#mainImage\",\"width\":800,\"height\":584},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\\\/#mainImage\"},\"datePublished\":\"2014-06-09T10:14:01+02:00\",\"dateModified\":\"2014-06-09T10:14:01+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i | El Digital de Asturias","description":"Shangh\u00e1i (China), 9 jun (EFE).- Una quincena de pel\u00edculas de 11 pa\u00edses, ninguna de ellas en espa\u00f1ol, competir\u00e1n este a\u00f1o en la decimos\u00e9ptima edici\u00f3n del Festival Internacional de Cine de Shangh\u00e1i (SIFF), el certamen m\u00e1s joven del mundo de clase A, que se celebrar\u00e1 en la capital econ\u00f3mica de China entre el 14 y el","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#article","name":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i | El Digital de Asturias","headline":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6345618w.jpg","width":800,"height":584},"datePublished":"2014-06-09T10:14:01+02:00","dateModified":"2014-06-09T10:14:01+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#listItem","name":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#listItem","position":3,"name":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/","name":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i | El Digital de Asturias","description":"Shangh\u00e1i (China), 9 jun (EFE).- Una quincena de pel\u00edculas de 11 pa\u00edses, ninguna de ellas en espa\u00f1ol, competir\u00e1n este a\u00f1o en la decimos\u00e9ptima edici\u00f3n del Festival Internacional de Cine de Shangh\u00e1i (SIFF), el certamen m\u00e1s joven del mundo de clase A, que se celebrar\u00e1 en la capital econ\u00f3mica de China entre el 14 y el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6345618w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#mainImage","width":800,"height":584},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/#mainImage"},"datePublished":"2014-06-09T10:14:01+02:00","dateModified":"2014-06-09T10:14:01+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i | El Digital de Asturias","og:description":"Shangh\u00e1i (China), 9 jun (EFE).- Una quincena de pel\u00edculas de 11 pa\u00edses, ninguna de ellas en espa\u00f1ol, competir\u00e1n este a\u00f1o en la decimos\u00e9ptima edici\u00f3n del Festival Internacional de Cine de Shangh\u00e1i (SIFF), el certamen m\u00e1s joven del mundo de clase A, que se celebrar\u00e1 en la capital econ\u00f3mica de China entre el 14 y el","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6345618w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6345618w.jpg","og:image:width":800,"og:image:height":584,"article:published_time":"2014-06-09T12:14:01+00:00","article:modified_time":"2014-06-09T12:14:01+00:00","twitter:card":"summary_large_image","twitter:title":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i | El Digital de Asturias","twitter:description":"Shangh\u00e1i (China), 9 jun (EFE).- Una quincena de pel\u00edculas de 11 pa\u00edses, ninguna de ellas en espa\u00f1ol, competir\u00e1n este a\u00f1o en la decimos\u00e9ptima edici\u00f3n del Festival Internacional de Cine de Shangh\u00e1i (SIFF), el certamen m\u00e1s joven del mundo de clase A, que se celebrar\u00e1 en la capital econ\u00f3mica de China entre el 14 y el","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6345618w.jpg"},"aioseo_meta_data":{"post_id":"15385","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 12:18:54","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:02:55","updated":"2026-05-16 12:18:54"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/\" title=\"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i\">Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Una quincena de pel\u00edculas competir\u00e1n este a\u00f1o en Festival de Cine de Shangh\u00e1i","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/una-quincena-de-peliculas-competiran-este-ano-en-festival-de-cine-de-shanghai\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15385"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15386"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}