{"id":15221,"date":"2014-06-06T21:44:09","date_gmt":"2014-06-06T23:44:09","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15221"},"modified":"2014-06-06T21:44:09","modified_gmt":"2014-06-06T23:44:09","slug":"un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/","title":{"rendered":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15222\" alt=\"6342322w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-360x233.jpg\" width=\"360\" height=\"233\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-360x233.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-650x421.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-768x497.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-150x97.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-450x291.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-696x451.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-649x420.jpg 649w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-225x145.jpg 225w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\u00e1ndo y cu\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\u00f3venes creadores de OrionSky mediante una m\u00e1quina que se controla con una innovadora aplicaci\u00f3n de tel\u00e9fono m\u00f3vil.<\/p>\n<p>Juan Antonio P\u00e9rez y Ana L\u00f3pez Silanes ten\u00edan a su cuidado varios perros de Agility (una modalidad competitiva donde un gu\u00eda dirige a un perro sobre una serie de obst\u00e1culos) y de exposici\u00f3n, cuando se vieron en la necesidad de \u00absaber si los bichos estaban bien, tranquilos y atendidos\u00bb, cuando estaban fuera de casa.<\/p>\n<p>\u00abLos dos trabajamos fuera, as\u00ed que nos pusimos a buscar un producto que pudiera alimentarlos y tenerlos controlados cuando no estuvi\u00e9ramos en casa, y no lo hab\u00eda. As\u00ed que como somos gente del mundo de la inform\u00e1tica dijimos: pues vamos a hacerlo nosotros. Y as\u00ed naci\u00f3 OrionSky\u00bb, explica Ana a Efe con una sonrisa.<\/p>\n<p>Juan Antonio nos detalla orgulloso que uno de sus perros, Orion, es campe\u00f3n de Espa\u00f1a de un concurso de belleza de la Real Sociedad Canina, \u00aby \u00e9l es el que da nombre a este tinglado\u00bb.<\/p>\n<p>Y de la necesidad hicieron virtud, al crear un dispensador de comida inteligente con un sistema online que se puede manejar a trav\u00e9s de tu m\u00f3vil o tablet y con el que le marcas la cantidad de pienso que necesita ingerir tu mascota y las tomas diarias que quieres que reciba.<\/p>\n<p>Su idea ha sido elegida como uno de los negocios \u00abm\u00e1s brillantes y con m\u00e1s futuro\u00bb del Centro de Emprendedores de la Comunidad de Madrid, ubicado en Getafe, y han recibido asesoramiento y tutorizaci\u00f3n dentro del programa \u00abInicia tu proyecto\u00bb.<\/p>\n<p>Juan Antonio enumera c\u00f3mo la m\u00e1quina cuenta con un sensor de capacidad que te indica cu\u00e1nta comida queda en la tolva, un sensor que te informa de la temperatura ambiente que hay en la habitaci\u00f3n, y c\u00f3mo la aplicaci\u00f3n te env\u00eda alertas al m\u00f3vil avis\u00e1ndote del momento en el que el perro ha comido.<\/p>\n<p>\u00abLa ventaja de este aparato respecto a una tolva cl\u00e1sica es que si la dejas llena para que el perro coma, se puede pegar el atrac\u00f3n el primer d\u00eda, y luego pasarse tres d\u00edas sin comer. En cambio as\u00ed, tiene el hambre necesaria para cada comida y el pienso permanece muy poco tiempo en el plato, por lo que es muy limpio\u00bb, destaca.<\/p>\n<p>Actualmente se encuentran en fase de producci\u00f3n y ya tienen pedidos con algunos distribuidores, con lo que esperan que en unas seis u ocho semanas el producto est\u00e9 en las tiendas para que la gente pueda comprarlo, por un precio que rondar\u00e1 los 250 euros por cada Black Orion, que es el nombre del aparato.<\/p>\n<p>Ante la pregunta de si funciona, Ana responde: \u00abLo hemos tenido en una fase Beta de dos meses en dos criaderos de perros, para que destrozaran los equipos, los mordieran y ver si funcionaban o si hab\u00eda cualquier tipo de problema. Y han dado muy buen resultado, hemos terminado la fase Beta con todo en verde, as\u00ed que estamos muy contentos\u00bb.<\/p>\n<p>Pero la verdadera prueba de que su resultado es positivo es Agatha, la perrita de Ana y Juan Antonio (de raza Collie, como la famosa Lassie), vigorosa y atl\u00e9tica, y que responde con tres ladridos alegres y convencidos cuando Efe le cuestiona sobre su satisfacci\u00f3n con el invento.<\/p>\n<p>Jose I. Fern\u00e1ndez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\u00e1ndo y cu\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\u00f3venes creadores de OrionSky mediante una m\u00e1quina que se controla con una innovadora aplicaci\u00f3n de tel\u00e9fono<\/p>\n","protected":false},"author":1,"featured_media":15222,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15221","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\u00e1ndo y cu\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\u00f3venes creadores de OrionSky mediante una m\u00e1quina que se controla con una innovadora aplicaci\u00f3n de tel\u00e9fono\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\u00e1ndo y cu\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\u00f3venes creadores de OrionSky mediante una m\u00e1quina que se controla con una innovadora aplicaci\u00f3n de tel\u00e9fono\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"518\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-06T23:44:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-06T23:44:09+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\u00e1ndo y cu\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\u00f3venes creadores de OrionSky mediante una m\u00e1quina que se controla con una innovadora aplicaci\u00f3n de tel\u00e9fono\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#article\",\"name\":\"Un invento con el que ya no necesitar\\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias\",\"headline\":\"Un invento con el que ya no necesitar\\u00e1s pedir al vecino que te cuide al perro\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6342322w.jpg\",\"width\":800,\"height\":518},\"datePublished\":\"2014-06-06T21:44:09+02:00\",\"dateModified\":\"2014-06-06T21:44:09+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#listItem\",\"name\":\"Un invento con el que ya no necesitar\\u00e1s pedir al vecino que te cuide al perro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#listItem\",\"position\":3,\"name\":\"Un invento con el que ya no necesitar\\u00e1s pedir al vecino que te cuide al perro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/\",\"name\":\"Un invento con el que ya no necesitar\\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias\",\"description\":\"Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\\u00e1ndo y cu\\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\\u00f3venes creadores de OrionSky mediante una m\\u00e1quina que se controla con una innovadora aplicaci\\u00f3n de tel\\u00e9fono\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6342322w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#mainImage\",\"width\":800,\"height\":518},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\\\/#mainImage\"},\"datePublished\":\"2014-06-06T21:44:09+02:00\",\"dateModified\":\"2014-06-06T21:44:09+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias","description":"Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\u00e1ndo y cu\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\u00f3venes creadores de OrionSky mediante una m\u00e1quina que se controla con una innovadora aplicaci\u00f3n de tel\u00e9fono","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#article","name":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias","headline":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w.jpg","width":800,"height":518},"datePublished":"2014-06-06T21:44:09+02:00","dateModified":"2014-06-06T21:44:09+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#listItem","name":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#listItem","position":3,"name":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/","name":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias","description":"Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\u00e1ndo y cu\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\u00f3venes creadores de OrionSky mediante una m\u00e1quina que se controla con una innovadora aplicaci\u00f3n de tel\u00e9fono","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#mainImage","width":800,"height":518},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/#mainImage"},"datePublished":"2014-06-06T21:44:09+02:00","dateModified":"2014-06-06T21:44:09+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias","og:description":"Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\u00e1ndo y cu\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\u00f3venes creadores de OrionSky mediante una m\u00e1quina que se controla con una innovadora aplicaci\u00f3n de tel\u00e9fono","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w.jpg","og:image:width":800,"og:image:height":518,"article:published_time":"2014-06-06T23:44:09+00:00","article:modified_time":"2014-06-06T23:44:09+00:00","twitter:card":"summary_large_image","twitter:title":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro | El Digital de Asturias","twitter:description":"Getafe, 6 jun (EFE).- Poder dar de comer a tu perro cuantas veces necesite, saber cu\u00e1ndo y cu\u00e1nto ha comido o conocer la temperatura de su cuarto, sin necesidad de estar en casa, es lo que han conseguido los j\u00f3venes creadores de OrionSky mediante una m\u00e1quina que se controla con una innovadora aplicaci\u00f3n de tel\u00e9fono","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6342322w.jpg"},"aioseo_meta_data":{"post_id":"15221","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 11:57:02","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:04:49","updated":"2026-05-16 11:57:02"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/\" title=\"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro\">Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Un invento con el que ya no necesitar\u00e1s pedir al vecino que te cuide al perro","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/un-invento-con-el-que-ya-no-necesitaras-pedir-al-vecino-que-te-cuide-al-perro\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15221"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15222"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}