{"id":15212,"date":"2014-06-06T21:36:06","date_gmt":"2014-06-06T23:36:06","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15212"},"modified":"2014-06-06T21:36:06","modified_gmt":"2014-06-06T23:36:06","slug":"la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/","title":{"rendered":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15213\" alt=\"6341447w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-360x235.jpg\" width=\"360\" height=\"235\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-360x235.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-650x425.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-768x502.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-150x98.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-450x294.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-696x455.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-741x486.jpg 741w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-642x420.jpg 642w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\u00e1nico-estadounidense Christopher O&#8217;Neill, presentaron hoy por primera vez en un acto p\u00fablico a su hija, la princesa Leonor.<\/p>\n<p>El debut de Leonor Lilian Mar\u00eda, de tres meses y medio de edad, coincidi\u00f3 con el habitual acto de puertas abiertas en el Palacio Real de Estocolmo durante los festejos del D\u00eda Nacional de este pa\u00eds escandinavo.<\/p>\n<p>Acompa\u00f1ada de su esposo y ataviada con el traje tradicional, al igual que su hija, Magdalena sali\u00f3 con la peque\u00f1a en brazos ante cientos de curiosos que se congregaban en el patio de palacio.<\/p>\n<p>Y tras pronunciar un breve discurso, se retir\u00f3 de nuevo hasta esta tarde, cuando participar\u00e1 con el resto de la familia real en la gala en el parque de Skansen en Estocolmo.<\/p>\n<p>Leonor Lilian Mar\u00eda, que ocupa el quinto lugar en la l\u00ednea de sucesi\u00f3n al trono y es la segunda nieta de los reyes Carlos XVI Gustavo y Silvia, ser\u00e1 bautizada este domingo en la iglesia del palacio de Drottningholm en la capital sueca.<\/p>\n<p>Magdalena y O&#8217;Neill se casaron el 8 de junio del a\u00f1o pasado en Estocolmo tras una relaci\u00f3n de dos a\u00f1os.<\/p>\n<p>La pareja vive en Nueva York, adonde la princesa se traslad\u00f3 en 2010 tras romper con su anterior pareja, el abogado sueco Jonas Bergstr\u00f6m, y donde trabaja para la fundaci\u00f3n fundada y presidida por su madre, la reina Silvia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\u00e1nico-estadounidense Christopher O&#8217;Neill, presentaron hoy por primera vez en un acto p\u00fablico a su hija, la princesa Leonor. El debut de Leonor Lilian Mar\u00eda, de tres meses y medio de edad, coincidi\u00f3 con el habitual acto de puertas abiertas en el<\/p>\n","protected":false},"author":1,"featured_media":15213,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15212","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\u00e1nico-estadounidense Christopher O&#039;Neill, presentaron hoy por primera vez en un acto p\u00fablico a su hija, la princesa Leonor. El debut de Leonor Lilian Mar\u00eda, de tres meses y medio de edad, coincidi\u00f3 con el habitual acto de puertas abiertas en el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\u00e1nico-estadounidense Christopher O&#039;Neill, presentaron hoy por primera vez en un acto p\u00fablico a su hija, la princesa Leonor. El debut de Leonor Lilian Mar\u00eda, de tres meses y medio de edad, coincidi\u00f3 con el habitual acto de puertas abiertas en el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-06T23:36:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-06T23:36:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\u00e1nico-estadounidense Christopher O&#039;Neill, presentaron hoy por primera vez en un acto p\u00fablico a su hija, la princesa Leonor. El debut de Leonor Lilian Mar\u00eda, de tres meses y medio de edad, coincidi\u00f3 con el habitual acto de puertas abiertas en el\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#article\",\"name\":\"La princesa Magdalena presenta a su hija Leonor en el D\\u00eda Nacional de Suecia | El Digital de Asturias\",\"headline\":\"La princesa Magdalena presenta a su hija Leonor en el D\\u00eda Nacional de Suecia\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6341447w.jpg\",\"width\":800,\"height\":523},\"datePublished\":\"2014-06-06T21:36:06+02:00\",\"dateModified\":\"2014-06-06T21:36:06+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#listItem\",\"name\":\"La princesa Magdalena presenta a su hija Leonor en el D\\u00eda Nacional de Suecia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#listItem\",\"position\":3,\"name\":\"La princesa Magdalena presenta a su hija Leonor en el D\\u00eda Nacional de Suecia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/\",\"name\":\"La princesa Magdalena presenta a su hija Leonor en el D\\u00eda Nacional de Suecia | El Digital de Asturias\",\"description\":\"Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\\u00e1nico-estadounidense Christopher O'Neill, presentaron hoy por primera vez en un acto p\\u00fablico a su hija, la princesa Leonor. El debut de Leonor Lilian Mar\\u00eda, de tres meses y medio de edad, coincidi\\u00f3 con el habitual acto de puertas abiertas en el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6341447w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#mainImage\",\"width\":800,\"height\":523},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\\\/#mainImage\"},\"datePublished\":\"2014-06-06T21:36:06+02:00\",\"dateModified\":\"2014-06-06T21:36:06+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia | El Digital de Asturias","description":"Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\u00e1nico-estadounidense Christopher O'Neill, presentaron hoy por primera vez en un acto p\u00fablico a su hija, la princesa Leonor. El debut de Leonor Lilian Mar\u00eda, de tres meses y medio de edad, coincidi\u00f3 con el habitual acto de puertas abiertas en el","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#article","name":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia | El Digital de Asturias","headline":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w.jpg","width":800,"height":523},"datePublished":"2014-06-06T21:36:06+02:00","dateModified":"2014-06-06T21:36:06+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#listItem","name":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#listItem","position":3,"name":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/","name":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia | El Digital de Asturias","description":"Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\u00e1nico-estadounidense Christopher O'Neill, presentaron hoy por primera vez en un acto p\u00fablico a su hija, la princesa Leonor. El debut de Leonor Lilian Mar\u00eda, de tres meses y medio de edad, coincidi\u00f3 con el habitual acto de puertas abiertas en el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#mainImage","width":800,"height":523},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/#mainImage"},"datePublished":"2014-06-06T21:36:06+02:00","dateModified":"2014-06-06T21:36:06+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia | El Digital de Asturias","og:description":"Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\u00e1nico-estadounidense Christopher O'Neill, presentaron hoy por primera vez en un acto p\u00fablico a su hija, la princesa Leonor. El debut de Leonor Lilian Mar\u00eda, de tres meses y medio de edad, coincidi\u00f3 con el habitual acto de puertas abiertas en el","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w.jpg","og:image:width":800,"og:image:height":523,"article:published_time":"2014-06-06T23:36:06+00:00","article:modified_time":"2014-06-06T23:36:06+00:00","twitter:card":"summary_large_image","twitter:title":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia | El Digital de Asturias","twitter:description":"Copenhague, 6 jun (EFE).- La princesa Magdalena de Suecia y su esposo, el financiero brit\u00e1nico-estadounidense Christopher O'Neill, presentaron hoy por primera vez en un acto p\u00fablico a su hija, la princesa Leonor. El debut de Leonor Lilian Mar\u00eda, de tres meses y medio de edad, coincidi\u00f3 con el habitual acto de puertas abiertas en el","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341447w.jpg"},"aioseo_meta_data":{"post_id":"15212","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 11:55:20","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:04:49","updated":"2026-05-16 11:55:20"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/\" title=\"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia\">La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"La princesa Magdalena presenta a su hija Leonor en el D\u00eda Nacional de Suecia","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-princesa-magdalena-presenta-a-su-hija-leonor-en-el-dia-nacional-de-suecia\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15212"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15213"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}