{"id":15208,"date":"2014-06-06T19:22:41","date_gmt":"2014-06-06T21:22:41","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15208"},"modified":"2014-06-06T19:22:41","modified_gmt":"2014-06-06T21:22:41","slug":"la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/","title":{"rendered":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15209\" alt=\"6341860w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341860w-360x239.jpg\" width=\"360\" height=\"239\" \/>Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\u00f3tica \u00abnecesita modelos inteligentes m\u00e1s cercanos a los humanos\u00bb en el contexto de lo que se llama \u00abinteligencia emocional\u00bb, dada la importancia de que los robots recojan informaci\u00f3n en el medio en el que se desenvuelven.<\/p>\n<p>La XII Conferencia Internacional de Aplicaciones Pr\u00e1cticas de Agentes y Sistemas Multiagente (PAAMS), que se ha clausurado en la capital salmantina ha puesto de manifiesto, en palabras del presidente del comit\u00e9 organizador, Juan Manuel Corchado, la relaci\u00f3n de la inteligencia artificial con \u00e1reas como la dependencia, la educaci\u00f3n o la formaci\u00f3n universitaria.<\/p>\n<p>En este sentido, el tambi\u00e9n vicerrector de Investigaci\u00f3n y Transferencia de la Universidad de Salamanca ha recordado en una rueda de prensa que la inteligencia artificial \u00abva muy de la mano de la rob\u00f3tica\u00bb.<\/p>\n<p>Ha trasladado la necesidad de que existan \u00abmodelos inteligentes y m\u00e1s cercanos a los humanos en el contexto de lo que se llama \u00abinteligencia emocional\u00bb.<\/p>\n<p>Ha insistido en que rob\u00f3tica ya no es s\u00f3lo construir robots, sino que \u00abuna parte muy importante es la capacidad de recoger informaci\u00f3n del medio\u00bb en el que se desenvuelven o incluso de \u00abfuentes ajenas\u00bb, entre las que ha mencionado internet.<\/p>\n<p>A su juicio, se trata de \u00abgestionar mucha informaci\u00f3n en tiempo real y muchos datos\u00bb y, en este sentido, \u00abes fundamental el an\u00e1lisis de todo ello y la utilizaci\u00f3n de t\u00e9cnicas de inteligencia artificial para crear algo que sea m\u00e1s parecido a un humano\u00bb.<\/p>\n<p>Las jornadas de trabajo han puesto de manifiesto, ha destacado Corchado, que este tipo de tecnolog\u00edas es fundamental en \u00e1mbitos como el financiero o el sanitario e incluso se pueden utilizar para manejar veh\u00edculos el\u00e9ctricos.<\/p>\n<p>El vicerrector ha expresado el convencimiento de que, cada vez m\u00e1s, \u00abla inteligencia artificial va a estar detr\u00e1s de cualquier aplicaci\u00f3n\u00bb.<\/p>\n<p>De ah\u00ed, el desarrollo de toda una serie de plataformas por parte de empresas, entre ellas IBM, que lo que hacen es decir al usuario \u00abqu\u00e9 datos tienes, cu\u00e1l es tu problema y aqu\u00ed te pongo una serie de t\u00e9cnicas a tu disposici\u00f3n para resolverlo en tiempo real\u00bb, ha reflexionado.<\/p>\n<p>La XII Conferencia Internacional ha contado con la asistencia del clon cibern\u00e9tico (robot) del profesor Hiroshi Ishiguro, catedr\u00e1tico de la Universidad de Osaka y l\u00edder del Laboratorio de Telecomunicaciones Avanzadas que lleva su nombre en Jap\u00f3n.<\/p>\n<p>De nombre Geminoid HI-4 presenta la gran novedad de ser un robot m\u00f3vil, que puede ser f\u00e1cilmente desplazado a distintas localizaciones y que tiene la capacidad de poder conversar con humanos, incorpora 12 servomotores para controlar la expresi\u00f3n facial, y posee adem\u00e1s capacidad de movimiento de los ojos.<\/p>\n<p>De hecho, a preguntas de los periodistas y en lengua espa\u00f1ola, ha resaltado la satisfacci\u00f3n de haber sido invitado a las sesiones de trabajo, as\u00ed como \u00abla gran discusi\u00f3n\u00bb habida entre los investigadores que han participado en el congreso.<\/p>\n<p>Por su parte, el copresidente del comit\u00e9 cient\u00edfico y presidente de la Asociaci\u00f3n Francesa de Inteligencia Artificial, Yves Demazeau, y el director adjunto de SONY Computer Science Laboratory Paris (Francia), Fran\u00e7ois Pachet, han coincidido en resaltar el papel de la \u00e9tica en el desarrollo de este tipo de aplicaciones.<\/p>\n<p>En este sentido, han abogado por definir \u00abun dise\u00f1o de aquellos elementos que mantengan un nivel de \u00e9tica exigible\u00bb, aunque han incidido en que \u00ablos aspectos morales dependen de cada pa\u00eds y de cada poblaci\u00f3n\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\u00f3tica \u00abnecesita modelos inteligentes m\u00e1s cercanos a los humanos\u00bb en el contexto de lo que se llama \u00abinteligencia emocional\u00bb, dada la importancia de que los robots recojan informaci\u00f3n en el medio en el que se desenvuelven. La XII Conferencia<\/p>\n","protected":false},"author":1,"featured_media":15209,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15208","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\u00f3tica &quot;necesita modelos inteligentes m\u00e1s cercanos a los humanos&quot; en el contexto de lo que se llama &quot;inteligencia emocional&quot;, dada la importancia de que los robots recojan informaci\u00f3n en el medio en el que se desenvuelven. La XII Conferencia\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\u00f3tica &quot;necesita modelos inteligentes m\u00e1s cercanos a los humanos&quot; en el contexto de lo que se llama &quot;inteligencia emocional&quot;, dada la importancia de que los robots recojan informaci\u00f3n en el medio en el que se desenvuelven. La XII Conferencia\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341860w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341860w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-06T21:22:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-06T21:22:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\u00f3tica &quot;necesita modelos inteligentes m\u00e1s cercanos a los humanos&quot; en el contexto de lo que se llama &quot;inteligencia emocional&quot;, dada la importancia de que los robots recojan informaci\u00f3n en el medio en el que se desenvuelven. La XII Conferencia\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341860w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#article\",\"name\":\"La rob\\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias\",\"headline\":\"La rob\\u00f3tica, en busca de modelos inteligentes cercanos a los humanos\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6341860w.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2014-06-06T19:22:41+02:00\",\"dateModified\":\"2014-06-06T19:22:41+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#listItem\",\"name\":\"La rob\\u00f3tica, en busca de modelos inteligentes cercanos a los humanos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#listItem\",\"position\":3,\"name\":\"La rob\\u00f3tica, en busca de modelos inteligentes cercanos a los humanos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/\",\"name\":\"La rob\\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias\",\"description\":\"Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\\u00f3tica \\\"necesita modelos inteligentes m\\u00e1s cercanos a los humanos\\\" en el contexto de lo que se llama \\\"inteligencia emocional\\\", dada la importancia de que los robots recojan informaci\\u00f3n en el medio en el que se desenvuelven. La XII Conferencia\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6341860w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\\\/#mainImage\"},\"datePublished\":\"2014-06-06T19:22:41+02:00\",\"dateModified\":\"2014-06-06T19:22:41+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias","description":"Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\u00f3tica \"necesita modelos inteligentes m\u00e1s cercanos a los humanos\" en el contexto de lo que se llama \"inteligencia emocional\", dada la importancia de que los robots recojan informaci\u00f3n en el medio en el que se desenvuelven. La XII Conferencia","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#article","name":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias","headline":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341860w.jpg","width":800,"height":533},"datePublished":"2014-06-06T19:22:41+02:00","dateModified":"2014-06-06T19:22:41+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#listItem","name":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#listItem","position":3,"name":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/","name":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias","description":"Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\u00f3tica \"necesita modelos inteligentes m\u00e1s cercanos a los humanos\" en el contexto de lo que se llama \"inteligencia emocional\", dada la importancia de que los robots recojan informaci\u00f3n en el medio en el que se desenvuelven. La XII Conferencia","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341860w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/#mainImage"},"datePublished":"2014-06-06T19:22:41+02:00","dateModified":"2014-06-06T19:22:41+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias","og:description":"Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\u00f3tica &quot;necesita modelos inteligentes m\u00e1s cercanos a los humanos&quot; en el contexto de lo que se llama &quot;inteligencia emocional&quot;, dada la importancia de que los robots recojan informaci\u00f3n en el medio en el que se desenvuelven. La XII Conferencia","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341860w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341860w.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2014-06-06T21:22:41+00:00","article:modified_time":"2014-06-06T21:22:41+00:00","twitter:card":"summary_large_image","twitter:title":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos | El Digital de Asturias","twitter:description":"Salamanca, 6 jun (EFE).- Expertos en inteligencia artificial han coincidido hoy en Salamanca en que la rob\u00f3tica &quot;necesita modelos inteligentes m\u00e1s cercanos a los humanos&quot; en el contexto de lo que se llama &quot;inteligencia emocional&quot;, dada la importancia de que los robots recojan informaci\u00f3n en el medio en el que se desenvuelven. La XII Conferencia","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6341860w.jpg"},"aioseo_meta_data":{"post_id":"15208","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 11:55:18","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:04:49","updated":"2026-05-16 11:55:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/\" title=\"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos\">La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"La rob\u00f3tica, en busca de modelos inteligentes cercanos a los humanos","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-robotica-en-busca-de-modelos-inteligentes-cercanos-a-los-humanos\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15208"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15209"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}