{"id":15123,"date":"2014-06-05T13:56:42","date_gmt":"2014-06-05T15:56:42","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15123"},"modified":"2014-06-05T13:56:42","modified_gmt":"2014-06-05T15:56:42","slug":"los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/","title":{"rendered":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15124\" alt=\"6336777w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6336777w-360x238.jpg\" width=\"360\" height=\"238\" \/>Madrid, 5 jun (EFE).- La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda (AEP) ha cargado contra los responsables de la pol\u00edtica sanitaria que les han acusado de \u00abrecomendar vacunas por intereses econ\u00f3micos\u00bb, ya que los casos de varicela han aumentado un 16 % este a\u00f1o respecto a 2013, seg\u00fan el Instituto de Salud Carlos III.<\/p>\n<p>Los pediatras han resaltado que este a\u00f1o, hasta el pasado 4 de mayo, se han registrado en torno a 9.000 casos m\u00e1s que el a\u00f1o pasado, un total de 63.136 afectados frente a los 54.173 de 2013.<\/p>\n<p>Esta denuncia se ha producido en el Congreso Extraordinario de la AEP, donde los expertos han asegurado que quienes asocian la defensa de la vacuna de la varicela a un \u00abconflicto de intereses\u00bb son los mismos que establecen sus pol\u00edticas \u00aben funci\u00f3n de objetivos econ\u00f3micos cortoplacistas\u00bb.<\/p>\n<p>Han insistido en que este tipo de comentarios son una \u00ababsoluta irresponsabilidad\u00bb que pretende justificar unas pol\u00edticas \u00abno basadas en criterios cient\u00edficos\u00bb.<\/p>\n<p>\u00abEncima se permiten el lujo de socavar la credibilidad del m\u00e9dico que atiende a los ni\u00f1os\u00bb, ha agregado el vicepresidente de AEP, Antonio Nieto, quien ha asegurado que \u00abafortunadamente los m\u00e9dicos son los m\u00e1s apreciados por los espa\u00f1oles\u00bb frente a los \u00ab\u00faltimos de la lista, que todos sabemos quienes son\u00bb, en referencia a los pol\u00edticos.<\/p>\n<p>Por su parte, Antonio Jurado, presidente del Comit\u00e9 Cient\u00edfico de este Congreso que se celebra en Madrid entre el 5 y el 7 de junio, y en el que participan 2.000 pediatras, se ha mostrado indignado y \u00abfrancamente dolido\u00bb con este tipo de declaraciones, y ha rechazado que los m\u00e9dicos recomienden vacunas para satisfacer sus intereses econ\u00f3micos, un \u00abcraso error\u00bb desde su punto de vista.<\/p>\n<p>\u00ab\u00bfAcaso existe un conflicto de intereses cuando un ni\u00f1o tiene neumon\u00eda y recetamos penicilina? \u00bfPor qu\u00e9 tenemos conflicto de intereses con la vacuna de la varicela y no con la del neumococo?\u00bb, ha planteado.<\/p>\n<p>El doctor Jurado ha insistido en que la vacuna contra esta enfermedad es \u00abmoralmente obligatoria\u00bb y debe administrarse entre los 12 y 15 meses (primera dosis) y entre los 3 y 4 a\u00f1os (segunda dosis).<\/p>\n<p>Otro de los temas que preocupa a los facultativos tiene que ver con el aumento de los beb\u00e9s prematuros, que representan entre el 8 % y el 9 % de nacimientos y suelen padecer patolog\u00edas metab\u00f3licas, infecciones, alteraciones neurol\u00f3gicas y problemas respiratorios \u00abpor falta de maduraci\u00f3n de los pulmones\u00bb, ha explicado Jurado.<\/p>\n<p>Los prematuros tard\u00edos, que nacen a las 34-36 semanas de gestaci\u00f3n, tambi\u00e9n tienen riesgo de sufrir complicaciones y en ellos influyen factores como la diabetes, la obesidad, las fecundaciones dirigidas o el hecho de que las mujeres den a luz cada vez m\u00e1s tarde.<\/p>\n<p>En cuanto al c\u00e1ncer infantil, el pediatra ha se\u00f1alado que cada a\u00f1os se registran 1.100 tumores malignos en ni\u00f1os de entre 0 y 14 a\u00f1os, aunque la supervivencia se estima en un 80 %.<\/p>\n<p>El 25 % de estos pacientes oncol\u00f3gicos padece leucemia, el 20 % sufre una enfermedad tumorales del sistema nervioso y al 15 % le detectan un linfoma, ha detallado Jurado, quien tambi\u00e9n ha cifrado la mejora de la mortalidad en un 47 % gracias a \u00abtratamientos m\u00e1s eficaces y m\u00e1s pediatras especializados en oncolog\u00eda\u00bb.<\/p>\n<p>Por otro lado, el doctor Nieto ha dicho que entre el 20 % y el 25 % de los ni\u00f1os padece alg\u00fan tipo de alergia y ha considerado que los accidentes como el del ni\u00f1o que muri\u00f3 por anafilaxia en una granja escuela de Villanueva de Perales (Madrid) son \u00abevitables\u00bb con una adecuada formaci\u00f3n y medidas preventivas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 5 jun (EFE).- La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda (AEP) ha cargado contra los responsables de la pol\u00edtica sanitaria que les han acusado de \u00abrecomendar vacunas por intereses econ\u00f3micos\u00bb, ya que los casos de varicela han aumentado un 16 % este a\u00f1o respecto a 2013, seg\u00fan el Instituto de Salud Carlos III. Los pediatras han<\/p>\n","protected":false},"author":1,"featured_media":15124,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15123","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 5 jun (EFE).- La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda (AEP) ha cargado contra los responsables de la pol\u00edtica sanitaria que les han acusado de &quot;recomendar vacunas por intereses econ\u00f3micos&quot;, ya que los casos de varicela han aumentado un 16 % este a\u00f1o respecto a 2013, seg\u00fan el Instituto de Salud Carlos III. Los pediatras han\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 5 jun (EFE).- La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda (AEP) ha cargado contra los responsables de la pol\u00edtica sanitaria que les han acusado de &quot;recomendar vacunas por intereses econ\u00f3micos&quot;, ya que los casos de varicela han aumentado un 16 % este a\u00f1o respecto a 2013, seg\u00fan el Instituto de Salud Carlos III. Los pediatras han\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6336777w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6336777w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-05T15:56:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-05T15:56:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 5 jun (EFE).- La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda (AEP) ha cargado contra los responsables de la pol\u00edtica sanitaria que les han acusado de &quot;recomendar vacunas por intereses econ\u00f3micos&quot;, ya que los casos de varicela han aumentado un 16 % este a\u00f1o respecto a 2013, seg\u00fan el Instituto de Salud Carlos III. Los pediatras han\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6336777w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#article\",\"name\":\"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\\u00e9s | El Digital de Asturias\",\"headline\":\"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\\u00e9s\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6336777w.jpg\",\"width\":800,\"height\":531},\"datePublished\":\"2014-06-05T13:56:42+02:00\",\"dateModified\":\"2014-06-05T13:56:42+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#listItem\",\"name\":\"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\\u00e9s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#listItem\",\"position\":3,\"name\":\"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\\u00e9s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/\",\"name\":\"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\\u00e9s | El Digital de Asturias\",\"description\":\"Madrid, 5 jun (EFE).- La Asociaci\\u00f3n Espa\\u00f1ola de Pediatr\\u00eda (AEP) ha cargado contra los responsables de la pol\\u00edtica sanitaria que les han acusado de \\\"recomendar vacunas por intereses econ\\u00f3micos\\\", ya que los casos de varicela han aumentado un 16 % este a\\u00f1o respecto a 2013, seg\\u00fan el Instituto de Salud Carlos III. Los pediatras han\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6336777w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#mainImage\",\"width\":800,\"height\":531},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\\\/#mainImage\"},\"datePublished\":\"2014-06-05T13:56:42+02:00\",\"dateModified\":\"2014-06-05T13:56:42+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s | El Digital de Asturias","description":"Madrid, 5 jun (EFE).- La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda (AEP) ha cargado contra los responsables de la pol\u00edtica sanitaria que les han acusado de \"recomendar vacunas por intereses econ\u00f3micos\", ya que los casos de varicela han aumentado un 16 % este a\u00f1o respecto a 2013, seg\u00fan el Instituto de Salud Carlos III. Los pediatras han","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#article","name":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s | El Digital de Asturias","headline":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6336777w.jpg","width":800,"height":531},"datePublished":"2014-06-05T13:56:42+02:00","dateModified":"2014-06-05T13:56:42+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#listItem","name":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#listItem","position":3,"name":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/","name":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s | El Digital de Asturias","description":"Madrid, 5 jun (EFE).- La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda (AEP) ha cargado contra los responsables de la pol\u00edtica sanitaria que les han acusado de \"recomendar vacunas por intereses econ\u00f3micos\", ya que los casos de varicela han aumentado un 16 % este a\u00f1o respecto a 2013, seg\u00fan el Instituto de Salud Carlos III. Los pediatras han","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6336777w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#mainImage","width":800,"height":531},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/#mainImage"},"datePublished":"2014-06-05T13:56:42+02:00","dateModified":"2014-06-05T13:56:42+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s | El Digital de Asturias","og:description":"Madrid, 5 jun (EFE).- La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda (AEP) ha cargado contra los responsables de la pol\u00edtica sanitaria que les han acusado de &quot;recomendar vacunas por intereses econ\u00f3micos&quot;, ya que los casos de varicela han aumentado un 16 % este a\u00f1o respecto a 2013, seg\u00fan el Instituto de Salud Carlos III. Los pediatras han","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6336777w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6336777w.jpg","og:image:width":800,"og:image:height":531,"article:published_time":"2014-06-05T15:56:42+00:00","article:modified_time":"2014-06-05T15:56:42+00:00","twitter:card":"summary_large_image","twitter:title":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s | El Digital de Asturias","twitter:description":"Madrid, 5 jun (EFE).- La Asociaci\u00f3n Espa\u00f1ola de Pediatr\u00eda (AEP) ha cargado contra los responsables de la pol\u00edtica sanitaria que les han acusado de &quot;recomendar vacunas por intereses econ\u00f3micos&quot;, ya que los casos de varicela han aumentado un 16 % este a\u00f1o respecto a 2013, seg\u00fan el Instituto de Salud Carlos III. Los pediatras han","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6336777w.jpg"},"aioseo_meta_data":{"post_id":"15123","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 11:45:37","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:05:51","updated":"2026-05-16 11:45:37"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/\" title=\"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s\">Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Los pediatras cargan contra quien les acusa de recomendar vacunas por inter\u00e9s","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-pediatras-cargan-contra-quien-les-acusa-de-recomendar-vacunas-por-interes\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15123"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15124"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}