{"id":15090,"date":"2014-06-05T10:11:53","date_gmt":"2014-06-05T12:11:53","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15090"},"modified":"2014-06-05T10:11:53","modified_gmt":"2014-06-05T12:11:53","slug":"documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/","title":{"rendered":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15091\" alt=\"6335938w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w-360x242.jpg\" width=\"360\" height=\"242\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w-360x242.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w-650x437.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w-768x516.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w-150x101.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w-450x303.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w-696x468.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w-625x420.jpg 625w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Lima, 4 jun (EFE).- Los pueblos ind\u00edgenas que protestaron hace cinco a\u00f1os en Bagua, en la selva de Per\u00fa, para que les restablezcan sus derechos sobre la tierra \u00absiguen totalmente indignados\u00bb porque las condiciones se mantienen, dijo el cineasta Fernando V\u00edlchez, director del documental \u00abLa Espera\u00bb, que se presentar\u00e1 este jueves.<\/p>\n<p>El documental se presentar\u00e1 en Lima.<\/p>\n<p>Las condiciones que generaron las protestas de los awaj\u00fan \u00abest\u00e1n casi exactamente igual, y podr\u00eda suceder de nuevo\u00bb, coment\u00f3 V\u00edlchez a Efe sobre las manifestaciones en Bagua que, despu\u00e9s de 50 d\u00edas de bloqueos, termin\u00f3 en violentos enfrentamientos con 33 muertos, entre polic\u00edas y civiles, y un agente policial desaparecido.<\/p>\n<p>Las comunidades ind\u00edgenas iniciaron una masiva protesta en abril del 2009 contra un paquete de leyes aprobada por el Gobierno de Alan Garc\u00eda (2006-2011) que buscaba incentivar las actividades extractivas en la Amazon\u00eda.<\/p>\n<p>El entonces Ejecutivo de Garc\u00eda acus\u00f3 a los dirigentes ind\u00edgenas de oponerse al desarrollo del pa\u00eds y sus ministros defend\u00edan las normas bajo el argumento de que eran necesarias para firmar el Tratado de Libre Comercio con Estados Unidos.<\/p>\n<p>Tras las muertes en Bagua, el Gobierno derog\u00f3 las leyes y aprob\u00f3 la ley de consulta previa, pero ha limitado su aplicaci\u00f3n a determinadas regiones.<\/p>\n<p>\u00abQue no haya responsables pol\u00edticos, que no haya inter\u00e9s en investigar, m\u00e1s all\u00e1 de lo poco que se hace, termina siendo incluso peor\u00bb, afirm\u00f3 el cineasta, tras recordar que los \u00fanicos procesados por las muertes son ind\u00edgenas.<\/p>\n<p>El documental de V\u00edlchez comenz\u00f3 a ser producido en 2011, dos a\u00f1os despu\u00e9s de los hechos, cuando el director se traslad\u00f3 a Bagua para ofrecer un taller de v\u00eddeo a las comunidades y encontr\u00f3 much\u00edsima informaci\u00f3n sobre el \u00abBaguazo\u00bb, como se conoci\u00f3 a la protesta.<\/p>\n<p>\u00abLa Espera\u00bb presenta un informe de la Inspector\u00eda de la Polic\u00eda Nacional que se\u00f1ala que la entonces ministra del Interior, Mercedes Cabanillas, nombr\u00f3 al oficial Luis Muguruza como jefe de un operativo de desalojo de una carretera tomada, dos d\u00edas antes del 5 de junio de 2009, fecha en que se produjeron los violentos enfrentamientos.<\/p>\n<p>El violento desalojo se realiz\u00f3 a pesar de que los ind\u00edgenas hab\u00edan decidido levantar los bloqueos porque el gobierno no atend\u00eda su demanda de derogar las leyes que rechazaban.<\/p>\n<p>Cabanillas neg\u00f3 en ese entonces haber dado la orden de reprimir a los manifestantes.<\/p>\n<p>V\u00edlchez dijo que el informe \u00abno es una prueba contundente, pero s\u00ed te dice mucho del \u00e1nimo y de los testimonios de los polic\u00edas sobre c\u00f3mo los estaban enviando (a controlar la protesta) sin equipos, sin alimentaci\u00f3n y sin comunicaci\u00f3n\u00bb.<\/p>\n<p>Seg\u00fan el director, \u00abhubo polic\u00edas en Bagua que dispararon contra civiles en la ciudad, pero nunca se ha probado que fueron polic\u00edas, porque todas las balas se recogieron de los hospitales y no hay ninguna prueba\u00bb.<\/p>\n<p>Los polic\u00edas tambi\u00e9n fueron v\u00edctimas en la protesta ya que 12 agentes murieron en una base petrolera que hab\u00eda sido tomada por los manifestantes y uno est\u00e1 desaparecido hasta el d\u00eda de hoy.<\/p>\n<p>Los familiares de los polic\u00edas muertos en el \u00abBaguazo\u00bb han afirmado, en un comunicado entregado a Efe, que es \u00abinaceptable\u00bb que el juicio a los jefes de la Polic\u00eda y autoridades del entonces gobierno que ordenaron el desalojo en la carretera \u00aba\u00fan no se inicie por la lenidad del Ministerio P\u00fablico\u00bb.<\/p>\n<p>Adem\u00e1s, \u00abla Fiscal\u00eda no ha hecho absolutamente nada por iniciar el proceso judicial por la matanza de los 12 polic\u00edas en la Estaci\u00f3n 6 de PetroPer\u00fa\u00bb.<\/p>\n<p>Los deudos exigen que la exministra Cabanillas asuma su responsabilidad pol\u00edtica y penal por la matanza del 5 de junio de 2009.<\/p>\n<p>El documental, de una hora y media de duraci\u00f3n, ser\u00e1 presentado en 22 salas de centros culturales, universidades y cine clubes de Lima, as\u00ed como en salas de Argentina, Brasil, Colombia, Ecuador y Bolivia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 4 jun (EFE).- Los pueblos ind\u00edgenas que protestaron hace cinco a\u00f1os en Bagua, en la selva de Per\u00fa, para que les restablezcan sus derechos sobre la tierra \u00absiguen totalmente indignados\u00bb porque las condiciones se mantienen, dijo el cineasta Fernando V\u00edlchez, director del documental \u00abLa Espera\u00bb, que se presentar\u00e1 este jueves. El documental se presentar\u00e1<\/p>\n","protected":false},"author":1,"featured_media":15091,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15090","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lima, 4 jun (EFE).- Los pueblos ind\u00edgenas que protestaron hace cinco a\u00f1os en Bagua, en la selva de Per\u00fa, para que les restablezcan sus derechos sobre la tierra &quot;siguen totalmente indignados&quot; porque las condiciones se mantienen, dijo el cineasta Fernando V\u00edlchez, director del documental &quot;La Espera&quot;, que se presentar\u00e1 este jueves. El documental se presentar\u00e1\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Lima, 4 jun (EFE).- Los pueblos ind\u00edgenas que protestaron hace cinco a\u00f1os en Bagua, en la selva de Per\u00fa, para que les restablezcan sus derechos sobre la tierra &quot;siguen totalmente indignados&quot; porque las condiciones se mantienen, dijo el cineasta Fernando V\u00edlchez, director del documental &quot;La Espera&quot;, que se presentar\u00e1 este jueves. El documental se presentar\u00e1\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"538\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-05T12:11:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-05T12:11:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lima, 4 jun (EFE).- Los pueblos ind\u00edgenas que protestaron hace cinco a\u00f1os en Bagua, en la selva de Per\u00fa, para que les restablezcan sus derechos sobre la tierra &quot;siguen totalmente indignados&quot; porque las condiciones se mantienen, dijo el cineasta Fernando V\u00edlchez, director del documental &quot;La Espera&quot;, que se presentar\u00e1 este jueves. El documental se presentar\u00e1\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#article\",\"name\":\"Documental sobre protesta ind\\u00edgena en Per\\u00fa se\\u00f1ala que la indignaci\\u00f3n sigue viva | El Digital de Asturias\",\"headline\":\"Documental sobre protesta ind\\u00edgena en Per\\u00fa se\\u00f1ala que la indignaci\\u00f3n sigue viva\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6335938w.jpg\",\"width\":800,\"height\":538},\"datePublished\":\"2014-06-05T10:11:53+02:00\",\"dateModified\":\"2014-06-05T10:11:53+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#listItem\",\"name\":\"Documental sobre protesta ind\\u00edgena en Per\\u00fa se\\u00f1ala que la indignaci\\u00f3n sigue viva\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#listItem\",\"position\":3,\"name\":\"Documental sobre protesta ind\\u00edgena en Per\\u00fa se\\u00f1ala que la indignaci\\u00f3n sigue viva\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/\",\"name\":\"Documental sobre protesta ind\\u00edgena en Per\\u00fa se\\u00f1ala que la indignaci\\u00f3n sigue viva | El Digital de Asturias\",\"description\":\"Lima, 4 jun (EFE).- Los pueblos ind\\u00edgenas que protestaron hace cinco a\\u00f1os en Bagua, en la selva de Per\\u00fa, para que les restablezcan sus derechos sobre la tierra \\\"siguen totalmente indignados\\\" porque las condiciones se mantienen, dijo el cineasta Fernando V\\u00edlchez, director del documental \\\"La Espera\\\", que se presentar\\u00e1 este jueves. El documental se presentar\\u00e1\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6335938w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#mainImage\",\"width\":800,\"height\":538},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\\\/#mainImage\"},\"datePublished\":\"2014-06-05T10:11:53+02:00\",\"dateModified\":\"2014-06-05T10:11:53+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva | El Digital de Asturias","description":"Lima, 4 jun (EFE).- Los pueblos ind\u00edgenas que protestaron hace cinco a\u00f1os en Bagua, en la selva de Per\u00fa, para que les restablezcan sus derechos sobre la tierra \"siguen totalmente indignados\" porque las condiciones se mantienen, dijo el cineasta Fernando V\u00edlchez, director del documental \"La Espera\", que se presentar\u00e1 este jueves. El documental se presentar\u00e1","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#article","name":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva | El Digital de Asturias","headline":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w.jpg","width":800,"height":538},"datePublished":"2014-06-05T10:11:53+02:00","dateModified":"2014-06-05T10:11:53+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#listItem","name":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#listItem","position":3,"name":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/","name":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva | El Digital de Asturias","description":"Lima, 4 jun (EFE).- Los pueblos ind\u00edgenas que protestaron hace cinco a\u00f1os en Bagua, en la selva de Per\u00fa, para que les restablezcan sus derechos sobre la tierra \"siguen totalmente indignados\" porque las condiciones se mantienen, dijo el cineasta Fernando V\u00edlchez, director del documental \"La Espera\", que se presentar\u00e1 este jueves. El documental se presentar\u00e1","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#mainImage","width":800,"height":538},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/#mainImage"},"datePublished":"2014-06-05T10:11:53+02:00","dateModified":"2014-06-05T10:11:53+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva | El Digital de Asturias","og:description":"Lima, 4 jun (EFE).- Los pueblos ind\u00edgenas que protestaron hace cinco a\u00f1os en Bagua, en la selva de Per\u00fa, para que les restablezcan sus derechos sobre la tierra &quot;siguen totalmente indignados&quot; porque las condiciones se mantienen, dijo el cineasta Fernando V\u00edlchez, director del documental &quot;La Espera&quot;, que se presentar\u00e1 este jueves. El documental se presentar\u00e1","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w.jpg","og:image:width":800,"og:image:height":538,"article:published_time":"2014-06-05T12:11:53+00:00","article:modified_time":"2014-06-05T12:11:53+00:00","twitter:card":"summary_large_image","twitter:title":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva | El Digital de Asturias","twitter:description":"Lima, 4 jun (EFE).- Los pueblos ind\u00edgenas que protestaron hace cinco a\u00f1os en Bagua, en la selva de Per\u00fa, para que les restablezcan sus derechos sobre la tierra &quot;siguen totalmente indignados&quot; porque las condiciones se mantienen, dijo el cineasta Fernando V\u00edlchez, director del documental &quot;La Espera&quot;, que se presentar\u00e1 este jueves. El documental se presentar\u00e1","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6335938w.jpg"},"aioseo_meta_data":{"post_id":"15090","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 11:40:10","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:06:42","updated":"2026-05-16 11:40:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/\" title=\"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva\">Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Documental sobre protesta ind\u00edgena en Per\u00fa se\u00f1ala que la indignaci\u00f3n sigue viva","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/documental-sobre-protesta-indigena-en-peru-senala-que-la-indignacion-sigue-viva\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15090"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15091"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}