{"id":14814,"date":"2014-06-02T23:46:03","date_gmt":"2014-06-03T01:46:03","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=14814"},"modified":"2014-06-02T23:46:03","modified_gmt":"2014-06-03T01:46:03","slug":"pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/","title":{"rendered":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-14815\" alt=\"6325734w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6325734w-360x247.jpg\" width=\"360\" height=\"247\" \/>Madrid, 2 jun (EFE).- Antonio Manuel \u00c1lvarez V\u00e9lez es presumido, \u00abpitingo\u00bb en cal\u00f3, flamenco y \u00abmovido\u00bb desde la cuna, y ha tenido que ser padre para \u00abtranquilizarse\u00bb y darse el gusto de \u00abcambiar de tercio\u00bb, como ha llamado su nuevo disco, demostrando que si antes no era m\u00e1s \u00abjondo\u00bb era porque no quer\u00eda, no porque no supiera.<\/p>\n<p>\u00abCambio de tercio\u00bb, que sale a la venta ma\u00f1ana, son colombianas, fandanguillos, tanguillos, ca\u00f1a, tangos, zambra, seguiriyas, buler\u00edas, sol\u00e9a y bamberas, es decir, \u00abflamenco en rama\u00bb pasado por un tamiz que le han ayudado a mover Estrella, Sole\u00e1 y Jos\u00e9 Enrique Morente, Arc\u00e1ngel, Miguel Poveda, Carmen Linares, Rafael Riqueni, Juan Carmona, Alfredo Lagos, Tomasito, Dorantes y Sara Baras.<\/p>\n<p>\u00abNo he hecho este disco por darles el gusto a los puristas, sino porque me apetec\u00eda. Ha sido un proceso creativo muy largo y han participado todos estos artistas en \u00e9l porque llev\u00e1bamos mucho tiempo diciendo &#8216;a ver si hacemos algo juntos&#8217;. Ha salido de forma natural porque nos conocemos desde hace mucho y nos admiramos mutuamente\u00bb, revela en una entrevista con Efe.<\/p>\n<p>Est\u00e1 \u00abmuy satisfecho\u00bb con el resultado. Han sido dos a\u00f1os de trabajo pero cada cosa del disco est\u00e1 como quer\u00eda y le ha apetecido \u00abmuch\u00edsimo hacer cada una de ellas\u00bb, explica el artista, al que fascina, por sus \u00abmuchos melismas\u00bb, el tema que ha hecho con Dorantes y Farah Siraj, \u00abLeilah\u00bb.<\/p>\n<p>Para ello ha tenido que aprender \u00e1rabe y dice que le gusta tanto como estudiar m\u00fasica e ingl\u00e9s, un idioma que le hace \u00abfalta\u00bb porque, detalla este artista que \u00abcontrola\u00bb el godspell -en el disco incluye \u00abSong of Joy\u00bb-, que ha cantado para la Fundaci\u00f3n Alas, la de Shakira, un tema con Eric Clapton, est\u00e1 viendo claro que hay futuro en Estados Unidos, donde actuar\u00e1 en septiembre.<\/p>\n<p>Pitingo (1980, Ayamonte, Huelva) es el de \u00abSouler\u00eda\u00bb y el de \u00abMalec\u00f3n Street\u00bb, su anterior disco, es decir, un s\u00faper ventas, pero cuando empezaba cant\u00f3 \u00abmucho, mucho\u00bb para el baile, es decir, desde atr\u00e1s, y ha visto lo que se puede y lo que no se puede hacer.<\/p>\n<p>\u00abEl peor pecado de un artista es hablar mal de los dem\u00e1s. Si lo hace es porque tiene mucho que callar de s\u00ed mismo. Esos cantaores que juzgan&#8230; para eso est\u00e1n los jueces\u00bb, sostiene.<\/p>\n<p>Confiesa que cuando ten\u00eda 18 a\u00f1os corr\u00eda a los quioscos a comprar los peri\u00f3dicos para ver qu\u00e9 dec\u00edan de su actuaci\u00f3n, y que ha llorado \u00abtela\u00bb, sobre todo cuando los comentarios le buscaban el cuerpo en una especie de vendetta, pero ahora no: \u00absoy fuerte, he madurado, he aprendido tambi\u00e9n de muchas cr\u00edticas y, sobre todo, me he centrado en la respuesta del p\u00fablico\u00bb.<\/p>\n<p>\u00c9l, que canta en la ca\u00f1a \u00abSerrano balc\u00f3n de Ronda\u00bb \u00aba m\u00ed me pueden mandar a servir a Dios y al Rey, pero dejar a tu persona \u00a1eso no lo manda nadie!\u00bb, no tiene opini\u00f3n, porque en eso \u00abno se mete\u00bb, sobre la abdicaci\u00f3n de don Juan Carlos, aunque, admite, le da \u00abpena\u00bb.<\/p>\n<p>El disco, en el que dedica a Paco de Luc\u00eda y Enrique Morente el tema de Luis Eduardo Aute \u00abDe alguna manera\u00bb, es tambi\u00e9n \u00abel debut\u00bb de su hijo Manuel, de dos a\u00f1os, y que con solo 8 meses, asevera, \u00abya hac\u00eda armon\u00edas\u00bb.<\/p>\n<p>Aqu\u00ed hace, al comienzo y al final, el quej\u00edo de un tema con el que no caben equivocaciones, \u00abY lleg\u00f3 Manuel (Momento pap\u00e1), y es que como \u00e9l dice en los agradecimientos, el cr\u00edo es su \u00absegunda piel\u00bb y el que ha devuelto \u00absensatez y cari\u00f1o\u00bb a su vida.<\/p>\n<p>Pero la declaraci\u00f3n de \u00abamor\u00bb m\u00e1s curiosa es la que ha provocado en Roger Waters, l\u00edder de Pink Floyd, al que conoci\u00f3 cuando grababa su a\u00fan in\u00e9dita aportaci\u00f3n a la Fundaci\u00f3n Alas.<\/p>\n<p>\u00abEs un artista flamenco buen\u00edsimo; un genio y no deber\u00edan perd\u00e9rselo\u00bb, asegura Waters en un v\u00eddeo grabado por su compa\u00f1\u00eda discogr\u00e1fica, Universal, con motivo de la salida del disco del espa\u00f1ol.<\/p>\n<p>&nbsp;<\/p>\n<p>Por Concha Barrig\u00f3s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 2 jun (EFE).- Antonio Manuel \u00c1lvarez V\u00e9lez es presumido, \u00abpitingo\u00bb en cal\u00f3, flamenco y \u00abmovido\u00bb desde la cuna, y ha tenido que ser padre para \u00abtranquilizarse\u00bb y darse el gusto de \u00abcambiar de tercio\u00bb, como ha llamado su nuevo disco, demostrando que si antes no era m\u00e1s \u00abjondo\u00bb era porque no quer\u00eda, no porque<\/p>\n","protected":false},"author":1,"featured_media":14815,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-14814","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 2 jun (EFE).- Antonio Manuel \u00c1lvarez V\u00e9lez es presumido, &quot;pitingo&quot; en cal\u00f3, flamenco y &quot;movido&quot; desde la cuna, y ha tenido que ser padre para &quot;tranquilizarse&quot; y darse el gusto de &quot;cambiar de tercio&quot;, como ha llamado su nuevo disco, demostrando que si antes no era m\u00e1s &quot;jondo&quot; era porque no quer\u00eda, no porque\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 2 jun (EFE).- Antonio Manuel \u00c1lvarez V\u00e9lez es presumido, &quot;pitingo&quot; en cal\u00f3, flamenco y &quot;movido&quot; desde la cuna, y ha tenido que ser padre para &quot;tranquilizarse&quot; y darse el gusto de &quot;cambiar de tercio&quot;, como ha llamado su nuevo disco, demostrando que si antes no era m\u00e1s &quot;jondo&quot; era porque no quer\u00eda, no porque\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6325734w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6325734w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-03T01:46:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-03T01:46:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 2 jun (EFE).- Antonio Manuel \u00c1lvarez V\u00e9lez es presumido, &quot;pitingo&quot; en cal\u00f3, flamenco y &quot;movido&quot; desde la cuna, y ha tenido que ser padre para &quot;tranquilizarse&quot; y darse el gusto de &quot;cambiar de tercio&quot;, como ha llamado su nuevo disco, demostrando que si antes no era m\u00e1s &quot;jondo&quot; era porque no quer\u00eda, no porque\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6325734w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#article\",\"name\":\"Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias\",\"headline\":\"Pitingo declara que el peor pecado de un artista es hablar mal de los otros\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6325734w.jpg\",\"width\":800,\"height\":550},\"datePublished\":\"2014-06-02T23:46:03+02:00\",\"dateModified\":\"2014-06-02T23:46:03+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#listItem\",\"name\":\"Pitingo declara que el peor pecado de un artista es hablar mal de los otros\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#listItem\",\"position\":3,\"name\":\"Pitingo declara que el peor pecado de un artista es hablar mal de los otros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/\",\"name\":\"Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias\",\"description\":\"Madrid, 2 jun (EFE).- Antonio Manuel \\u00c1lvarez V\\u00e9lez es presumido, \\\"pitingo\\\" en cal\\u00f3, flamenco y \\\"movido\\\" desde la cuna, y ha tenido que ser padre para \\\"tranquilizarse\\\" y darse el gusto de \\\"cambiar de tercio\\\", como ha llamado su nuevo disco, demostrando que si antes no era m\\u00e1s \\\"jondo\\\" era porque no quer\\u00eda, no porque\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6325734w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#mainImage\",\"width\":800,\"height\":550},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\\\/#mainImage\"},\"datePublished\":\"2014-06-02T23:46:03+02:00\",\"dateModified\":\"2014-06-02T23:46:03+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias","description":"Madrid, 2 jun (EFE).- Antonio Manuel \u00c1lvarez V\u00e9lez es presumido, \"pitingo\" en cal\u00f3, flamenco y \"movido\" desde la cuna, y ha tenido que ser padre para \"tranquilizarse\" y darse el gusto de \"cambiar de tercio\", como ha llamado su nuevo disco, demostrando que si antes no era m\u00e1s \"jondo\" era porque no quer\u00eda, no porque","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#article","name":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias","headline":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6325734w.jpg","width":800,"height":550},"datePublished":"2014-06-02T23:46:03+02:00","dateModified":"2014-06-02T23:46:03+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#listItem","name":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#listItem","position":3,"name":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/","name":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias","description":"Madrid, 2 jun (EFE).- Antonio Manuel \u00c1lvarez V\u00e9lez es presumido, \"pitingo\" en cal\u00f3, flamenco y \"movido\" desde la cuna, y ha tenido que ser padre para \"tranquilizarse\" y darse el gusto de \"cambiar de tercio\", como ha llamado su nuevo disco, demostrando que si antes no era m\u00e1s \"jondo\" era porque no quer\u00eda, no porque","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6325734w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#mainImage","width":800,"height":550},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/#mainImage"},"datePublished":"2014-06-02T23:46:03+02:00","dateModified":"2014-06-02T23:46:03+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias","og:description":"Madrid, 2 jun (EFE).- Antonio Manuel \u00c1lvarez V\u00e9lez es presumido, &quot;pitingo&quot; en cal\u00f3, flamenco y &quot;movido&quot; desde la cuna, y ha tenido que ser padre para &quot;tranquilizarse&quot; y darse el gusto de &quot;cambiar de tercio&quot;, como ha llamado su nuevo disco, demostrando que si antes no era m\u00e1s &quot;jondo&quot; era porque no quer\u00eda, no porque","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6325734w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6325734w.jpg","og:image:width":800,"og:image:height":550,"article:published_time":"2014-06-03T01:46:03+00:00","article:modified_time":"2014-06-03T01:46:03+00:00","twitter:card":"summary_large_image","twitter:title":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros | El Digital de Asturias","twitter:description":"Madrid, 2 jun (EFE).- Antonio Manuel \u00c1lvarez V\u00e9lez es presumido, &quot;pitingo&quot; en cal\u00f3, flamenco y &quot;movido&quot; desde la cuna, y ha tenido que ser padre para &quot;tranquilizarse&quot; y darse el gusto de &quot;cambiar de tercio&quot;, como ha llamado su nuevo disco, demostrando que si antes no era m\u00e1s &quot;jondo&quot; era porque no quer\u00eda, no porque","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6325734w.jpg"},"aioseo_meta_data":{"post_id":"14814","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 11:08:13","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:09:41","updated":"2026-05-16 11:08:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/\" title=\"Pitingo declara que el peor pecado de un artista es hablar mal de los otros\">Pitingo declara que el peor pecado de un artista es hablar mal de los otros<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Pitingo declara que el peor pecado de un artista es hablar mal de los otros","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/pitingo-declara-que-el-peor-pecado-de-un-artista-es-hablar-mal-de-los-otros\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/14814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=14814"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/14814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/14815"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=14814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=14814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=14814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}