{"id":14763,"date":"2014-06-02T12:25:54","date_gmt":"2014-06-02T14:25:54","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=14763"},"modified":"2014-06-02T12:25:54","modified_gmt":"2014-06-02T14:25:54","slug":"japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/","title":{"rendered":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-14764\" alt=\"6324019w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6324019w-360x240.jpg\" width=\"360\" height=\"240\" \/>Tokio, 2 jun (EFE).- Una cadena de televisi\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\u00f3n 4K, lo que le convierte en el primer canal nip\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\u00f3n convencional (HD) para difusiones diarias.<\/p>\n<p>La iniciativa, respaldada por el Ejecutivo nip\u00f3n, servir\u00e1 para probar este nuevo formato con vistas a generalizar su uso comercial en 2016, seg\u00fan inform\u00f3 hoy la agencia japonesa Kyodo.<\/p>\n<p>El objetivo es \u00abmejorar la competitividad tecnol\u00f3gica\u00bb de Jap\u00f3n a nivel internacional m\u00e1s all\u00e1 de los productos de electr\u00f3nica de consumo, seg\u00fan explic\u00f3 el ministro de Gesti\u00f3n P\u00fablica, Asuntos Internos, Correos y Telecomunicaciones, Shindo Yoshitaka, en una reciente rueda de prensa sobre el 4K.<\/p>\n<p>La tecnolog\u00eda de ultra alta definici\u00f3n o 4K multiplica por cuatro el n\u00famero de p\u00edxeles de una pantalla de alta definici\u00f3n, de forma que la resoluci\u00f3n es cuatro veces superior al HD o alta definici\u00f3n convencional.<\/p>\n<p>Aunque este formato ya ha sido empleado en fase de pruebas en otros pa\u00edses, Jap\u00f3n fue uno de los pioneros en su desarrollo gracias a los proyectos llevados a cabo por la televisi\u00f3n estatal NHK en colaboraci\u00f3n con universidades niponas y con compa\u00f1\u00edas como Sony, Panasonic, Sharp o Toshiba.<\/p>\n<p>El canal nip\u00f3n en pruebas, llamado Channel 4K, est\u00e1 operado por la compa\u00f1\u00eda NexTV-F y en una primera etapa emitir\u00e1 contenidos gratuitos producidos por otras emisoras del grupo durante seis horas diarias.<\/p>\n<p>NexTV-F fue creada en mayo de 2013 con el objetivo de promover la televisi\u00f3n en este formato, y cuenta con la participaci\u00f3n de varios canales de televisi\u00f3n nipones, fabricantes de electr\u00f3nica y otros socios.<\/p>\n<p>M\u00e1s adelante, el Ejecutivo japon\u00e9s planea comenzar a probar tambi\u00e9n el 8K, el formato superior dentro de la ultra alta definici\u00f3n con 7680 \u00d7 4320 p\u00edxeles (33.2 megap\u00edxeles)-, con la mirada puesta en las retransmisiones internacionales de los Juegos Ol\u00edmpicos de Tokio 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tokio, 2 jun (EFE).- Una cadena de televisi\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\u00f3n 4K, lo que le convierte en el primer canal nip\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\u00f3n convencional (HD) para difusiones diarias. La iniciativa, respaldada por el Ejecutivo nip\u00f3n, servir\u00e1 para probar<\/p>\n","protected":false},"author":1,"featured_media":14764,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-14763","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tokio, 2 jun (EFE).- Una cadena de televisi\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\u00f3n 4K, lo que le convierte en el primer canal nip\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\u00f3n convencional (HD) para difusiones diarias. La iniciativa, respaldada por el Ejecutivo nip\u00f3n, servir\u00e1 para probar\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Tokio, 2 jun (EFE).- Una cadena de televisi\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\u00f3n 4K, lo que le convierte en el primer canal nip\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\u00f3n convencional (HD) para difusiones diarias. La iniciativa, respaldada por el Ejecutivo nip\u00f3n, servir\u00e1 para probar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6324019w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6324019w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-02T14:25:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-02T14:25:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tokio, 2 jun (EFE).- Una cadena de televisi\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\u00f3n 4K, lo que le convierte en el primer canal nip\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\u00f3n convencional (HD) para difusiones diarias. La iniciativa, respaldada por el Ejecutivo nip\u00f3n, servir\u00e1 para probar\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6324019w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#article\",\"name\":\"Jap\\u00f3n pone en marcha un canal de televisi\\u00f3n en alta definici\\u00f3n 4K | El Digital de Asturias\",\"headline\":\"Jap\\u00f3n pone en marcha un canal de televisi\\u00f3n en alta definici\\u00f3n 4K\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6324019w.jpg\",\"width\":800,\"height\":535},\"datePublished\":\"2014-06-02T12:25:54+02:00\",\"dateModified\":\"2014-06-02T12:25:54+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#listItem\",\"name\":\"Jap\\u00f3n pone en marcha un canal de televisi\\u00f3n en alta definici\\u00f3n 4K\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#listItem\",\"position\":3,\"name\":\"Jap\\u00f3n pone en marcha un canal de televisi\\u00f3n en alta definici\\u00f3n 4K\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/\",\"name\":\"Jap\\u00f3n pone en marcha un canal de televisi\\u00f3n en alta definici\\u00f3n 4K | El Digital de Asturias\",\"description\":\"Tokio, 2 jun (EFE).- Una cadena de televisi\\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\\u00f3n 4K, lo que le convierte en el primer canal nip\\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\\u00f3n convencional (HD) para difusiones diarias. La iniciativa, respaldada por el Ejecutivo nip\\u00f3n, servir\\u00e1 para probar\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6324019w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#mainImage\",\"width\":800,\"height\":535},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\\\/#mainImage\"},\"datePublished\":\"2014-06-02T12:25:54+02:00\",\"dateModified\":\"2014-06-02T12:25:54+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K | El Digital de Asturias","description":"Tokio, 2 jun (EFE).- Una cadena de televisi\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\u00f3n 4K, lo que le convierte en el primer canal nip\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\u00f3n convencional (HD) para difusiones diarias. La iniciativa, respaldada por el Ejecutivo nip\u00f3n, servir\u00e1 para probar","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#article","name":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K | El Digital de Asturias","headline":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6324019w.jpg","width":800,"height":535},"datePublished":"2014-06-02T12:25:54+02:00","dateModified":"2014-06-02T12:25:54+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#listItem","name":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#listItem","position":3,"name":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/","name":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K | El Digital de Asturias","description":"Tokio, 2 jun (EFE).- Una cadena de televisi\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\u00f3n 4K, lo que le convierte en el primer canal nip\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\u00f3n convencional (HD) para difusiones diarias. La iniciativa, respaldada por el Ejecutivo nip\u00f3n, servir\u00e1 para probar","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6324019w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#mainImage","width":800,"height":535},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/#mainImage"},"datePublished":"2014-06-02T12:25:54+02:00","dateModified":"2014-06-02T12:25:54+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K | El Digital de Asturias","og:description":"Tokio, 2 jun (EFE).- Una cadena de televisi\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\u00f3n 4K, lo que le convierte en el primer canal nip\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\u00f3n convencional (HD) para difusiones diarias. La iniciativa, respaldada por el Ejecutivo nip\u00f3n, servir\u00e1 para probar","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6324019w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6324019w.jpg","og:image:width":800,"og:image:height":535,"article:published_time":"2014-06-02T14:25:54+00:00","article:modified_time":"2014-06-02T14:25:54+00:00","twitter:card":"summary_large_image","twitter:title":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K | El Digital de Asturias","twitter:description":"Tokio, 2 jun (EFE).- Una cadena de televisi\u00f3n japonesa ha empezado a emitir hoy en ultra alta definici\u00f3n 4K, lo que le convierte en el primer canal nip\u00f3n que emplea este novedoso formato cuatro veces superior a la alta definici\u00f3n convencional (HD) para difusiones diarias. La iniciativa, respaldada por el Ejecutivo nip\u00f3n, servir\u00e1 para probar","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6324019w.jpg"},"aioseo_meta_data":{"post_id":"14763","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 11:01:26","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:10:42","updated":"2026-05-16 11:01:26"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/\" title=\"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K\">Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Jap\u00f3n pone en marcha un canal de televisi\u00f3n en alta definici\u00f3n 4K","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/japon-pone-en-marcha-un-canal-de-television-en-alta-definicion-4k\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/14763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=14763"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/14763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/14764"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=14763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=14763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=14763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}