{"id":14746,"date":"2014-06-01T23:13:08","date_gmt":"2014-06-02T01:13:08","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=14746"},"modified":"2014-06-01T23:13:08","modified_gmt":"2014-06-02T01:13:08","slug":"miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/","title":{"rendered":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-14747\" alt=\"6323490w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w-360x240.jpg\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w-650x434.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w-768x513.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w-696x465.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w-629x420.jpg 629w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros.<\/p>\n<p>La sexta edici\u00f3n lisboeta termina esta madrugada con la actuaci\u00f3n del estadounidense Justin Timberlake despu\u00e9s de cinco d\u00edas de leyendas rockeras como Rolling Stones, Linkin Park o Arcade Fire.<\/p>\n<p>En la recta final, los asistentes organizan su agenda para acceder a algunos de los servicios m\u00e1s codiciados del certamen.<\/p>\n<p>Los m\u00e1s atrevidos optan por lanzarse en tirolina a catorce metros de altura para recorrer 150 metros suspendidos en el aire sobre el escenario principal.<\/p>\n<p>La otra gran oferta es la noria de 27 metros de altura que domina desde los m\u00e1s alto las m\u00e1s de 85 hect\u00e1reas de colinas, c\u00e9sped y \u00e1rboles del Parque Bela Vista de Lisboa.<\/p>\n<p>Cerca de la atracci\u00f3n de feria, las casetas de la \u00abCiudad Rock\u00bb han concentrado a gran parte de los espectadores en sus calles prefabricadas, que emulan barrios de Londres y Dubl\u00edn con aparentes tabernas y algunos escenarios.<\/p>\n<p>En ellas, la sorpresa de hoy fue la boda de la periodista televisiva portuguesa Joana Latino, que se cas\u00f3 con zapatillas rojas y vestido de los a\u00f1os cincuenta.<\/p>\n<p>Pero lo m\u00e1s desafiante para los espectadores fueron las horas de colas que se necesitan para entrar a una peluquer\u00eda, conseguir regalos como sombreros o sillas de pl\u00e1stico o entrar a las tiendas.<\/p>\n<p>\u00abLlevamos tres horas en fila para conseguir un corte de pelo\u00bb, se\u00f1al\u00f3 a Efe Sara Proenca, de 21 a\u00f1os, en uno de los puestos m\u00e1s concurridos.<\/p>\n<p>Y es que el Rock in Rio, uno de los de mayor asistencia del mundo, se asemeja, abajo de los escenarios, a un parque tem\u00e1tico con una gran oferta de actividades, puestos de comida y espect\u00e1culos callejeros.<\/p>\n<p>Por ejemplo, bailarines de \u00abbreak dance\u00bb compitieron en un escenario que representaba el Bronx de Nueva York y m\u00fasicos celtas con faldas escocesas animaron la tarde a ni\u00f1os con violines y acordeones.<\/p>\n<p>Los grafiteros portugueses Jo\u00e3o Completo e Ivo Carvalho ofrecieron cada d\u00eda una nueva prueba de su arte en los muros de la \u00abStreet dance\u00bb.<\/p>\n<p>A la oferta habitual de comida r\u00e1pida, el festival a\u00f1adi\u00f3 cocina de chefs portugueses, as\u00ed como zonas de descanso con c\u00f3modos sof\u00e1s y ambientaci\u00f3n.<\/p>\n<p>Arriba de los escenarios, el exitoso modelo de festival sigue con conciertos masivos y buenas dosis de decibelios que hacen vibrar el suelo lisboeta.<\/p>\n<p>El Rock in Rio cumple este a\u00f1o su d\u00e9cimo aniversario en Lisboa y se trasladar\u00e1 el pr\u00f3ximo mayo a Las Vegas en la que ser\u00e1 su primera edici\u00f3n estadounidense.<\/p>\n<p>Fuentes de la organizaci\u00f3n estiman que m\u00e1s de 300.000 personas habr\u00e1n pasado por el festival al cierre, de los que cerca de 90.000 se concentraron el d\u00eda del concierto de Rolling Stones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros. La sexta edici\u00f3n lisboeta termina esta madrugada con la actuaci\u00f3n del<\/p>\n","protected":false},"author":1,"featured_media":14747,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-14746","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros. La sexta edici\u00f3n lisboeta termina esta madrugada con la actuaci\u00f3n del\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros. La sexta edici\u00f3n lisboeta termina esta madrugada con la actuaci\u00f3n del\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-02T01:13:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-02T01:13:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros. La sexta edici\u00f3n lisboeta termina esta madrugada con la actuaci\u00f3n del\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#article\",\"name\":\"Miles de personas aprovechan el ocio de lujo en las \\u00faltimas horas del Rock in Rio | El Digital de Asturias\",\"headline\":\"Miles de personas aprovechan el ocio de lujo en las \\u00faltimas horas del Rock in Rio\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6323490w.jpg\",\"width\":800,\"height\":534},\"datePublished\":\"2014-06-01T23:13:08+02:00\",\"dateModified\":\"2014-06-01T23:13:08+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#listItem\",\"name\":\"Miles de personas aprovechan el ocio de lujo en las \\u00faltimas horas del Rock in Rio\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#listItem\",\"position\":3,\"name\":\"Miles de personas aprovechan el ocio de lujo en las \\u00faltimas horas del Rock in Rio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/\",\"name\":\"Miles de personas aprovechan el ocio de lujo en las \\u00faltimas horas del Rock in Rio | El Digital de Asturias\",\"description\":\"Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \\u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros. La sexta edici\\u00f3n lisboeta termina esta madrugada con la actuaci\\u00f3n del\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6323490w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#mainImage\",\"width\":800,\"height\":534},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\\\/#mainImage\"},\"datePublished\":\"2014-06-01T23:13:08+02:00\",\"dateModified\":\"2014-06-01T23:13:08+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio | El Digital de Asturias","description":"Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros. La sexta edici\u00f3n lisboeta termina esta madrugada con la actuaci\u00f3n del","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#article","name":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio | El Digital de Asturias","headline":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w.jpg","width":800,"height":534},"datePublished":"2014-06-01T23:13:08+02:00","dateModified":"2014-06-01T23:13:08+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#listItem","name":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#listItem","position":3,"name":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/","name":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio | El Digital de Asturias","description":"Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros. La sexta edici\u00f3n lisboeta termina esta madrugada con la actuaci\u00f3n del","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#mainImage","width":800,"height":534},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/#mainImage"},"datePublished":"2014-06-01T23:13:08+02:00","dateModified":"2014-06-01T23:13:08+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio | El Digital de Asturias","og:description":"Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros. La sexta edici\u00f3n lisboeta termina esta madrugada con la actuaci\u00f3n del","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w.jpg","og:image:width":800,"og:image:height":534,"article:published_time":"2014-06-02T01:13:08+00:00","article:modified_time":"2014-06-02T01:13:08+00:00","twitter:card":"summary_large_image","twitter:title":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio | El Digital de Asturias","twitter:description":"Lisboa, 1 jun (EFE).- Miles de personas apuran hoy las \u00faltimas horas del Rock in Rio Lisboa para aprovechar el lado m\u00e1s ocioso del festival, desde asistir a una boda callejera a dejarse sorprender por un peluquero de renombre o aprender a grafitear muros. La sexta edici\u00f3n lisboeta termina esta madrugada con la actuaci\u00f3n del","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323490w.jpg"},"aioseo_meta_data":{"post_id":"14746","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 10:59:08","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:10:42","updated":"2026-05-16 10:59:08"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/\" title=\"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio\">Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Miles de personas aprovechan el ocio de lujo en las \u00faltimas horas del Rock in Rio","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/miles-de-personas-aprovechan-el-ocio-de-lujo-en-las-ultimas-horas-del-rock-in-rio\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/14746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=14746"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/14746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/14747"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=14746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=14746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=14746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}