{"id":14739,"date":"2014-06-01T21:03:49","date_gmt":"2014-06-01T23:03:49","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=14739"},"modified":"2014-06-01T21:03:49","modified_gmt":"2014-06-01T23:03:49","slug":"bunbury-inicia-en-valladolid-su-gira-espanola","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/","title":{"rendered":"Bunbury inicia en Valladolid su gira espa\u00f1ola"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-14740\" alt=\"6323298w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w-360x241.jpg\" width=\"360\" height=\"241\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w-360x241.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w-650x436.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w-768x515.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w-150x101.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w-450x302.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w-696x466.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w-627x420.jpg 627w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Valladolid, 1 jun (EFE).- La gira \u00abPalosanto Tour 2014\u00bb, de Enrique Bunbury, aterrizar\u00e1 en Espa\u00f1a el pr\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\u00edses iberoamericanos y con la previsi\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona.<\/p>\n<p>La gira internacional se inici\u00f3 el pasado enero en M\u00e9xico, donde Bunbury ofreci\u00f3 hasta trece conciertos en ocho ciudades y sum\u00f3 m\u00e1s de 100.000 seguidores, ha explicado hoy la compa\u00f1\u00eda RT Producciones a trav\u00e9s de un comunicado.<\/p>\n<p>Despu\u00e9s de la ronda mexicana, el cantante aragon\u00e9s prosigui\u00f3 su recorrido por Rep\u00fablica Dominicana, Guatemala, Honduras, El Salvador, Costa Rica, Colombia, Per\u00fa, Ecuador, Chile y Argentina, para completar un total de once conciertos.<\/p>\n<p>En Espa\u00f1a, los seguidores del vocalista de H\u00e9roes del Silencio podr\u00e1n acompa\u00f1arle en los conciertos de Valladolid (5 de junio), Santiago de Compostela (7 de junio), Granada (12 de junio), Sevilla (14 de junio), Barcelona (19 de junio), Zaragoza (21 de junio), Bilbao (27 de junio), Madrid (29 de junio) y Valencia (3 de julio).<\/p>\n<p>Pero los viajes no cesar\u00e1n para Bunbury, que tiene previsto ofrecer en septiembre hasta once conciertos en Estados Unidos y en octubre volver a M\u00e9xico para sumar su arte al del argentino Andr\u00e9s Calamaro, con quien compartir\u00e1 cinco conciertos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valladolid, 1 jun (EFE).- La gira \u00abPalosanto Tour 2014\u00bb, de Enrique Bunbury, aterrizar\u00e1 en Espa\u00f1a el pr\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\u00edses iberoamericanos y con la previsi\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona. La gira internacional se inici\u00f3 el pasado<\/p>\n","protected":false},"author":1,"featured_media":14740,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-14739","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Valladolid, 1 jun (EFE).- La gira &quot;Palosanto Tour 2014&quot;, de Enrique Bunbury, aterrizar\u00e1 en Espa\u00f1a el pr\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\u00edses iberoamericanos y con la previsi\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona. La gira internacional se inici\u00f3 el pasado\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Bunbury inicia en Valladolid su gira espa\u00f1ola | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Valladolid, 1 jun (EFE).- La gira &quot;Palosanto Tour 2014&quot;, de Enrique Bunbury, aterrizar\u00e1 en Espa\u00f1a el pr\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\u00edses iberoamericanos y con la previsi\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona. La gira internacional se inici\u00f3 el pasado\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-01T23:03:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-01T23:03:49+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Bunbury inicia en Valladolid su gira espa\u00f1ola | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Valladolid, 1 jun (EFE).- La gira &quot;Palosanto Tour 2014&quot;, de Enrique Bunbury, aterrizar\u00e1 en Espa\u00f1a el pr\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\u00edses iberoamericanos y con la previsi\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona. La gira internacional se inici\u00f3 el pasado\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#article\",\"name\":\"Bunbury inicia en Valladolid su gira espa\\u00f1ola | El Digital de Asturias\",\"headline\":\"Bunbury inicia en Valladolid su gira espa\\u00f1ola\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6323298w.jpg\",\"width\":800,\"height\":536},\"datePublished\":\"2014-06-01T21:03:49+02:00\",\"dateModified\":\"2014-06-01T21:03:49+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#listItem\",\"name\":\"Bunbury inicia en Valladolid su gira espa\\u00f1ola\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#listItem\",\"position\":3,\"name\":\"Bunbury inicia en Valladolid su gira espa\\u00f1ola\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/\",\"name\":\"Bunbury inicia en Valladolid su gira espa\\u00f1ola | El Digital de Asturias\",\"description\":\"Valladolid, 1 jun (EFE).- La gira \\\"Palosanto Tour 2014\\\", de Enrique Bunbury, aterrizar\\u00e1 en Espa\\u00f1a el pr\\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\\u00edses iberoamericanos y con la previsi\\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona. La gira internacional se inici\\u00f3 el pasado\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6323298w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#mainImage\",\"width\":800,\"height\":536},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bunbury-inicia-en-valladolid-su-gira-espanola\\\/#mainImage\"},\"datePublished\":\"2014-06-01T21:03:49+02:00\",\"dateModified\":\"2014-06-01T21:03:49+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Bunbury inicia en Valladolid su gira espa\u00f1ola | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Bunbury inicia en Valladolid su gira espa\u00f1ola | El Digital de Asturias","description":"Valladolid, 1 jun (EFE).- La gira \"Palosanto Tour 2014\", de Enrique Bunbury, aterrizar\u00e1 en Espa\u00f1a el pr\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\u00edses iberoamericanos y con la previsi\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona. La gira internacional se inici\u00f3 el pasado","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#article","name":"Bunbury inicia en Valladolid su gira espa\u00f1ola | El Digital de Asturias","headline":"Bunbury inicia en Valladolid su gira espa\u00f1ola","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w.jpg","width":800,"height":536},"datePublished":"2014-06-01T21:03:49+02:00","dateModified":"2014-06-01T21:03:49+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#listItem","name":"Bunbury inicia en Valladolid su gira espa\u00f1ola"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#listItem","position":3,"name":"Bunbury inicia en Valladolid su gira espa\u00f1ola","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/","name":"Bunbury inicia en Valladolid su gira espa\u00f1ola | El Digital de Asturias","description":"Valladolid, 1 jun (EFE).- La gira \"Palosanto Tour 2014\", de Enrique Bunbury, aterrizar\u00e1 en Espa\u00f1a el pr\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\u00edses iberoamericanos y con la previsi\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona. La gira internacional se inici\u00f3 el pasado","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#mainImage","width":800,"height":536},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/#mainImage"},"datePublished":"2014-06-01T21:03:49+02:00","dateModified":"2014-06-01T21:03:49+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Bunbury inicia en Valladolid su gira espa\u00f1ola | El Digital de Asturias","og:description":"Valladolid, 1 jun (EFE).- La gira &quot;Palosanto Tour 2014&quot;, de Enrique Bunbury, aterrizar\u00e1 en Espa\u00f1a el pr\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\u00edses iberoamericanos y con la previsi\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona. La gira internacional se inici\u00f3 el pasado","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w.jpg","og:image:width":800,"og:image:height":536,"article:published_time":"2014-06-01T23:03:49+00:00","article:modified_time":"2014-06-01T23:03:49+00:00","twitter:card":"summary_large_image","twitter:title":"Bunbury inicia en Valladolid su gira espa\u00f1ola | El Digital de Asturias","twitter:description":"Valladolid, 1 jun (EFE).- La gira &quot;Palosanto Tour 2014&quot;, de Enrique Bunbury, aterrizar\u00e1 en Espa\u00f1a el pr\u00f3ximo 5 de junio con el primer concierto en Valladolid, tras recorrer once pa\u00edses iberoamericanos y con la previsi\u00f3n de ofrecer nueve conciertos en ciudades entre las que figuran Madrid y Barcelona. La gira internacional se inici\u00f3 el pasado","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6323298w.jpg"},"aioseo_meta_data":{"post_id":"14739","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 10:58:02","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 08:10:42","updated":"2026-05-16 10:58:02"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/\" title=\"Bunbury inicia en Valladolid su gira espa\u00f1ola\">Bunbury inicia en Valladolid su gira espa\u00f1ola<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Bunbury inicia en Valladolid su gira espa\u00f1ola","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/bunbury-inicia-en-valladolid-su-gira-espanola\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/14739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=14739"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/14739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/14740"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=14739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=14739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=14739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}