{"id":108156,"date":"2022-02-10T15:25:23","date_gmt":"2022-02-10T15:25:23","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=108156"},"modified":"2022-02-10T15:25:23","modified_gmt":"2022-02-10T15:25:23","slug":"siemens-aumento-un-20-por-ciento-el-beneficio-neto","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/","title":{"rendered":"Siemens aument\u00f3 un 20 por ciento el beneficio neto"},"content":{"rendered":"<p>M\u00fanich, 10 feb (dpa) &#8211; El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros (2.100 millones de d\u00f3lares), inform\u00f3 hoy la compa\u00f1\u00eda antes de celebrar la Junta General de Accionistas.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-42478\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros-650x357.jpg\" alt=\"\" width=\"650\" height=\"357\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros-650x357.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros-360x198.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros-150x82.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros-450x247.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros.jpg 655w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Asimismo precis\u00f3 que el volumen de ventas aument\u00f3 un nueve por ciento, hasta 16.500 millones de euros (18.800 millones de d\u00f3lares). La cartera de pedidos creci\u00f3 un 42 por ciento en t\u00e9rminos comprables, hasta alcanzar los 24.200 millones de euros.<\/p>\n<p>El director ejecutivo del grupo alem\u00e1n, Roland Busch, expres\u00f3 satisfacci\u00f3n por el \u00abauge sin precedentes de nuevos pedidos\u00bb. Seg\u00fan Siemens, esto se debe a las compras adelantadas por parte de los clientes y tambi\u00e9n a los grandes pedidos de la divisi\u00f3n de movilidad.<\/p>\n<p>La empresa no mostr\u00f3 preocupaci\u00f3n con respecto a una posible cancelaci\u00f3n de pedidos adelantados. El director financiero Ralf P. Thomas explic\u00f3 que ya hay pagos anticipados para muchos pedidos y destac\u00f3 que las gestiones de compra se realizaron con el \u00abmismo grado de severidad\u00bb que de costumbre.<\/p>\n<p>Siemens anunci\u00f3 que no elevar\u00e1 esta vez su previsi\u00f3n, como lo hizo en reiteradas oportunidades el a\u00f1o pasado.<\/p>\n<p>Sin embargo, Thomas dijo que ve\u00eda potencial para alcanzar o incluso superar el m\u00e1ximo objetivo para las ganancias por acci\u00f3n. Agreg\u00f3 que dentro de tres meses, cuando se presenten las cifras del segundo trimestre, se actualizar\u00e1n las perspectivas.<\/p>\n<p>Siemens anunci\u00f3 a \u00faltima hora del mi\u00e9rcoles la venta de su negocio de paqueter\u00eda y correos y del 50 por ciento de su participaci\u00f3n en la empresa conjunta de coches el\u00e9ctricos con Valeo Siemens eAutomotive.<\/p>\n<p>El negocio de paqueter\u00eda y correos pasar\u00e1 al grupo tecnol\u00f3gico K\u00f6rber por 1.150 millones de euros (1.300 millones de d\u00f3lares).<\/p>\n<p>En tanto, Valeo se har\u00e1 cargo de la parte del socio de la empresa conjunta. Siemens espera que esto tenga un efecto positivo en las ganancias de 300 millones de euros en el actual segundo trimestre del a\u00f1o fiscal.<\/p>\n<p>La empresa conjunta se fund\u00f3 en 2016, cuando Siemens aport\u00f3 su negocio de sistemas de accionamiento para coches el\u00e9ctricos.<\/p>\n<p>Las noticias de Siemens fueron en general muy bien recibidas en el mercado burs\u00e1til alem\u00e1n. En las primera horas de la ma\u00f1ana el precio de la acci\u00f3n en el selectivo Dax subi\u00f3 por momentos m\u00e1s de un siete por ciento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fanich, 10 feb (dpa) &#8211; El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros (2.100 millones de d\u00f3lares), inform\u00f3 hoy la compa\u00f1\u00eda antes de celebrar la Junta General de Accionistas. Asimismo precis\u00f3 que el volumen de ventas aument\u00f3 un nueve por<\/p>\n","protected":false},"author":1,"featured_media":42478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[206],"tags":[355],"class_list":["post-108156","post","type-post","status-publish","format-standard","has-post-thumbnail","category-canal-empresas","tag-empresas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"empresas,canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Siemens aument\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-02-10T15:25:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-02-10T15:25:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Siemens aument\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#article\",\"name\":\"Siemens aument\\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias\",\"headline\":\"Siemens aument\\u00f3 un 20 por ciento el beneficio neto\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/euros.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2022-02-10T15:25:23+01:00\",\"dateModified\":\"2022-02-10T15:25:23+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#webpage\"},\"articleSection\":\"Canal Empresas, Empresas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#listItem\",\"name\":\"Siemens aument\\u00f3 un 20 por ciento el beneficio neto\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#listItem\",\"position\":3,\"name\":\"Siemens aument\\u00f3 un 20 por ciento el beneficio neto\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/\",\"name\":\"Siemens aument\\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias\",\"description\":\"El gigante electr\\u00f3nico alem\\u00e1n Siemens aument\\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/euros.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\\\/#mainImage\"},\"datePublished\":\"2022-02-10T15:25:23+01:00\",\"dateModified\":\"2022-02-10T15:25:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Siemens aument\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Siemens aument\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias","description":"El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/","robots":"max-image-preview:large","keywords":"empresas,canal empresas","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#article","name":"Siemens aument\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias","headline":"Siemens aument\u00f3 un 20 por ciento el beneficio neto","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros.jpg","width":655,"height":360},"datePublished":"2022-02-10T15:25:23+01:00","dateModified":"2022-02-10T15:25:23+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#webpage"},"articleSection":"Canal Empresas, Empresas"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#listItem","name":"Siemens aument\u00f3 un 20 por ciento el beneficio neto"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#listItem","position":3,"name":"Siemens aument\u00f3 un 20 por ciento el beneficio neto","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/","name":"Siemens aument\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias","description":"El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/#mainImage"},"datePublished":"2022-02-10T15:25:23+01:00","dateModified":"2022-02-10T15:25:23+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Siemens aument\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias","og:description":"El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2022-02-10T15:25:23+00:00","article:modified_time":"2022-02-10T15:25:23+00:00","twitter:card":"summary_large_image","twitter:title":"Siemens aument\u00f3 un 20 por ciento el beneficio neto | El Digital de Asturias","twitter:description":"El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/07\/euros.jpg"},"aioseo_meta_data":{"post_id":"108156","title":null,"description":"El gigante electr\u00f3nico alem\u00e1n Siemens aument\u00f3 un 20 por ciento el beneficio neto en el primer trimestre, hasta los 1.800 millones de euros","keywords":[],"keyphrases":{"focus":{"keyphrase":"Siemens ","score":80,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase not found in the URL.","score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Focus keyphrase in image alt attributes","description":"Focus keyphrase not found in image alt attribute(s). Add an image with your Focus keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},"additional":[{"keyphrase":" beneficio neto","score":83,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase not found in image alt attribute(s). Add an image with your Keyphrase as alt text.","score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 22:30:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-02-10 15:23:36","updated":"2026-05-26 22:30:04"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/\" title=\"Siemens aument\u00f3 un 20 por ciento el beneficio neto\">Siemens aument\u00f3 un 20 por ciento el beneficio neto<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Canal Empresas","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/"},{"label":"Siemens aument\u00f3 un 20 por ciento el beneficio neto","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/siemens-aumento-un-20-por-ciento-el-beneficio-neto\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/108156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=108156"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/108156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/42478"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=108156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=108156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=108156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}