{"id":107997,"date":"2022-01-07T08:40:58","date_gmt":"2022-01-07T08:40:58","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=107997"},"modified":"2022-01-07T08:40:58","modified_gmt":"2022-01-07T08:40:58","slug":"la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/","title":{"rendered":"La filial japonesa de McDonald&#8217;s racionar\u00e1 las patatas fritas"},"content":{"rendered":"<p>(EP) &#8211; La filial japonesa de<strong><a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/negocios-y-empresas\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"> McDonald&#8217;s<\/span> <\/a>ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes<\/strong>, \u00fanicamente servir\u00e1 en sus men\u00fas el formato peque\u00f1o de patatas fritas como consecuencia de los problemas de suministro y los retrasos que afectan al puerto de Vancouver (Canad\u00e1), principal punto de tr\u00e1nsito de las importaciones de la compa\u00f1\u00eda desde Norteam\u00e9rica.<\/p>\n<figure id=\"attachment_107998\" aria-describedby=\"caption-attachment-107998\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-107998 size-large\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds-650x457.jpg\" alt=\"McDonald's \" width=\"650\" height=\"457\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds-650x457.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds-360x253.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds-768x540.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds-150x105.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds-450x316.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds.jpg 959w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-107998\" class=\"wp-caption-text\">foto: MCDONALD&#8217;S \/ Europa Press<\/figcaption><\/figure>\n<p>De este modo, tal como se vio forzada a hacer entre el 24 y el 30 de diciembre del a\u00f1o pasado, la cadena de restaurantes de <a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/sabores\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>comida r\u00e1pida<\/strong><\/span><\/a> \u00fanicamente servir\u00e1 el &#8216;tama\u00f1o S&#8217; (peque\u00f1o) de patatas fritas en sus men\u00fas.<\/p>\n<p>\u00abSuspendemos temporalmente las ventas de los tama\u00f1os M y L (mediano y grande) a partir del 9 de enero de 2022 (domingo) durante aproximadamente un mes, y solo venderemos el tama\u00f1o S\u00bb, ha informado la empresa, a\u00f1adiendo que est\u00e1 tomando varias medidas para asegurarse un suministro estable en el futuro, como la organizaci\u00f3n de nuevos canales de distribuci\u00f3n.<\/p>\n<p>McDonald&#8217;s Japan ha explicado que importa patatas de Norteam\u00e9rica a gran escala a trav\u00e9s del puerto de Vancouver, pero los env\u00edos sufrieron retrasos debido a da\u00f1os provocados por inundaciones y al impacto del coronavirus en la red de distribuci\u00f3n global.<\/p>\n<p>Adem\u00e1s del continuo retraso en las importaciones, circunstancias imprevistas, como la retenci\u00f3n de la carga en Vancouver, los problemas causados por los efectos de la nieve y el mal tiempo en la ruta y el aplazamiento hasta mediados de enero del servicio de env\u00edo programado para principios de mes ha provocado un nuevo retraso en la llegada de suministros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; La filial japonesa de McDonald&#8217;s ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes, \u00fanicamente servir\u00e1 en sus men\u00fas el formato peque\u00f1o de patatas fritas como consecuencia de los problemas de suministro y los retrasos que afectan al puerto de Vancouver (Canad\u00e1), principal punto de tr\u00e1nsito de las importaciones<\/p>\n","protected":false},"author":1,"featured_media":107998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[206],"tags":[355,349],"class_list":["post-107997","post","type-post","status-publish","format-standard","has-post-thumbnail","category-canal-empresas","tag-empresas","tag-sabores"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La filial japonesa de McDonald&#039;s ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes, \u00fanicamente servir\u00e1 en sus men\u00fas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"empresas,sabores,canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La filial japonesa de McDonald&#039;s ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes, \u00fanicamente servir\u00e1 en sus men\u00fas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"959\" \/>\n\t\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-01-07T08:40:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-01-07T08:40:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La filial japonesa de McDonald&#039;s ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes, \u00fanicamente servir\u00e1 en sus men\u00fas\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#article\",\"name\":\"La filial japonesa de McDonald\\u2019s racionar\\u00e1 las patatas fritas | El Digital de Asturias\",\"headline\":\"La filial japonesa de McDonald&#8217;s racionar\\u00e1 las patatas fritas\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/McDonalds.jpg\",\"width\":959,\"height\":674,\"caption\":\"foto: MCDONALD'S \\\/ Europa Press\"},\"datePublished\":\"2022-01-07T08:40:58+01:00\",\"dateModified\":\"2022-01-07T08:40:58+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#webpage\"},\"articleSection\":\"Canal Empresas, Empresas, sabores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#listItem\",\"name\":\"La filial japonesa de McDonald&#8217;s racionar\\u00e1 las patatas fritas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#listItem\",\"position\":3,\"name\":\"La filial japonesa de McDonald&#8217;s racionar\\u00e1 las patatas fritas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1787856165\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/\",\"name\":\"La filial japonesa de McDonald\\u2019s racionar\\u00e1 las patatas fritas | El Digital de Asturias\",\"description\":\"La filial japonesa de McDonald's ha anunciado que, a partir del pr\\u00f3ximo domingo y durante aproximadamente un mes, \\u00fanicamente servir\\u00e1 en sus men\\u00fas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/McDonalds.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#mainImage\",\"width\":959,\"height\":674,\"caption\":\"foto: MCDONALD'S \\\/ Europa Press\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\\\/#mainImage\"},\"datePublished\":\"2022-01-07T08:40:58+01:00\",\"dateModified\":\"2022-01-07T08:40:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas | El Digital de Asturias","description":"La filial japonesa de McDonald's ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes, \u00fanicamente servir\u00e1 en sus men\u00fas","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/","robots":"max-image-preview:large","keywords":"empresas,sabores,canal empresas","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#article","name":"La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas | El Digital de Asturias","headline":"La filial japonesa de McDonald&#8217;s racionar\u00e1 las patatas fritas","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds.jpg","width":959,"height":674,"caption":"foto: MCDONALD'S \/ Europa Press"},"datePublished":"2022-01-07T08:40:58+01:00","dateModified":"2022-01-07T08:40:58+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#webpage"},"articleSection":"Canal Empresas, Empresas, sabores"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#listItem","name":"La filial japonesa de McDonald&#8217;s racionar\u00e1 las patatas fritas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#listItem","position":3,"name":"La filial japonesa de McDonald&#8217;s racionar\u00e1 las patatas fritas","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1787856165","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/","name":"La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas | El Digital de Asturias","description":"La filial japonesa de McDonald's ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes, \u00fanicamente servir\u00e1 en sus men\u00fas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#mainImage","width":959,"height":674,"caption":"foto: MCDONALD'S \/ Europa Press"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/#mainImage"},"datePublished":"2022-01-07T08:40:58+01:00","dateModified":"2022-01-07T08:40:58+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas | El Digital de Asturias","og:description":"La filial japonesa de McDonald's ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes, \u00fanicamente servir\u00e1 en sus men\u00fas","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds.jpg","og:image:width":959,"og:image:height":674,"article:published_time":"2022-01-07T08:40:58+00:00","article:modified_time":"2022-01-07T08:40:58+00:00","twitter:card":"summary_large_image","twitter:title":"La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas | El Digital de Asturias","twitter:description":"La filial japonesa de McDonald's ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes, \u00fanicamente servir\u00e1 en sus men\u00fas","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2022\/01\/McDonalds.jpg"},"aioseo_meta_data":{"post_id":"107997","title":null,"description":"La filial japonesa de McDonald's ha anunciado que, a partir del pr\u00f3ximo domingo y durante aproximadamente un mes, \u00fanicamente servir\u00e1 en sus men\u00fas &nbsp;","keywords":[],"keyphrases":{"focus":{"keyphrase":"McDonald's ","score":92,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase not found in the URL.","score":1,"maxScore":5,"error":1},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Focus keyphrase in image alt attributes","description":"Focus keyphrase found in image alt attribute(s).","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"filial japonesa","score":83,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase not found in image alt attribute(s). Add an image with your Keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"men\u00fas ","score":83,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase not found in image alt attribute(s). Add an image with your Keyphrase as alt text.","score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 22:19:17","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-01-07 08:32:52","updated":"2026-05-26 22:19:17","focus_keyword":"McDonald's","additional_keywords":[{"word":"filial japonesa","score":83},{"word":"men\u00fas","score":83}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/\" title=\"La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas\">La filial japonesa de McDonald\u2019s racionar\u00e1 las patatas fritas<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Canal Empresas","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/canal-empresas\/"},{"label":"La filial japonesa de McDonald&#8217;s racionar\u00e1 las patatas fritas","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-filial-japonesa-de-mcdonalds-racionara-las-patatas-fritas\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/107997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=107997"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/107997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/107998"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=107997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=107997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=107997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}