{"id":107645,"date":"2021-10-27T18:18:08","date_gmt":"2021-10-27T18:18:08","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=107645"},"modified":"2022-03-09T13:39:04","modified_gmt":"2022-03-09T13:39:04","slug":"como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/","title":{"rendered":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Se acerca el <\/span><b>d\u00eda de Todos los Santos<\/b><span style=\"font-weight: 400;\">, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente. Es una fecha para recordarles y honrar su memoria, bien c\u00f3mo para compartirlo con los que todav\u00eda pueden hacerlo.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-107646 size-large\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos-650x426.jpg\" alt=\"Todos los Santos\" width=\"650\" height=\"426\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos-650x426.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos-360x236.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos-150x98.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos-450x295.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos.jpg 698w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de las visitas a los cementerios de todo el pa\u00eds,<\/span><b> muchas familias se re\u00fanen estos d\u00edas<\/b><span style=\"font-weight: 400;\"> para compartir los buenos recuerdos. Con las redes sociales, ahora es posible hacerlo a distancia. Sin embargo, son redes generalistas, enfocadas al intercambio de contenidos de todo tipo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una empresa madrile\u00f1a ha identificado la necesidad de crear un espacio m\u00e1s especializado en la publicaci\u00f3n de recuerdos, para unir a personas con intereses y una realidad similar. As\u00ed naci\u00f3 <\/span><span style=\"color: #000000;\"><strong>www.livecobo.com<\/strong><\/span><span style=\"font-weight: 400;\">, <\/span><b>la primera red social <\/b><span style=\"font-weight: 400;\">de memoriales en l\u00ednea que permite la publicaci\u00f3n de recuerdos personalizados tanto de <\/span><b>personas como de mascotas<\/b><span style=\"font-weight: 400;\"> fallecidas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Su creador es el empresario<\/span><b> Alberto Cobo D\u00edaz<\/b><span style=\"font-weight: 400;\">. De ah\u00ed el nombre de la red LiveCobo, \u00abLive\u00bb, de la vida que mantenemos con ilusi\u00f3n, pasi\u00f3n, humildad y respeto, y Cobo por su propio apellido, heredado de su madre y antecesores, como un legado para sus propios descendientes. Seg\u00fan Alberto, su principal motivaci\u00f3n fue la de poder dar vida a los buenos recuerdos que ten\u00eda de sus parientes y amigos de su pueblo natal, que con el pasar de los a\u00f1os se van volviendo cada vez m\u00e1s lejanos. Seg\u00fan \u00e9l mismo dice:<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u00ab<\/span><i><span style=\"font-weight: 400;\">Mi pena surge cuando todos mis recuerdos se han simplificado a leves recuerdos de ciertos momentos. Me cuesta poner cara a mis abuelos y, mucho m\u00e1s, al resto de los vecinos del pueblo y de mi ciudad de los que, aunque guardo algunos recuerdos, no guardo ninguna fotograf\u00eda.<\/span><\/i><span style=\"font-weight: 400;\">\u00ab<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">En LiveCobo, cuyo desarrollo est\u00e1 a cargo de la empresa <\/span><a href=\"https:\/\/www.iberactiv.com\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"color: #ff6600;\"><b>Iberactiv<\/b><\/span><\/a><span style=\"font-weight: 400;\">, es posible compartir fotos, v\u00eddeos, sonidos, historias, enviar regalos virtuales y mucho m\u00e1s. Nos permite unir nuestra red de familiares y amigos para compartir esos buenos buenos momentos, ya sea por intereses comunes o por ubicaci\u00f3n geogr\u00e1fica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ofrece muchas posibilidades, aunque el eje central de esa plataforma es la publicaci\u00f3n de <\/span><b>p\u00e1ginas de recuerdos personalizadas de personas o mascotas<\/b><span style=\"font-weight: 400;\">. Por un lado, los usuarios que se registran pueden interactuar con otros usuarios registrados, como en cualquier otra red social. Por otro, pueden crear un perfil para cada persona o mascota fallecida. Esa p\u00e1gina de recuerdo es compartida con sus amigos en la red, que publican all\u00ed comentarios, fotos, v\u00eddeos y otros contenidos de esa persona o mascota. Cada vez que uno quiera recordar a esos seres queridos, entrar\u00e1 en esas p\u00e1ginas y ver\u00e1 lo que todos hayan compartido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n permite que un grupo de personas re\u00fana dinero para ayudar a las familias con los gastos del funeral, viajes y otros similares en virtud los los decesos, a trav\u00e9s de un servicio de <\/span><b>financiaci\u00f3n colectiva<\/b><span style=\"font-weight: 400;\"> (crowdfunding).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">LiveCobo ya funciona totalmente, y sigue en desarrollo para ofrecer <\/span><b>nuevas funcionalidades<\/b><span style=\"font-weight: 400;\"> que tambi\u00e9n ser\u00e1n \u00fatiles para sus usuarios. Entre estas, habr\u00e1 un mercado libre para art\u00edculos de segunda mano, una tienda online, una secci\u00f3n para publicar ofertas de trabajo y otra para que empresas del sector como aseguradoras, funerarias, florister\u00edas y otros puedan ofrecer sus servicios de forma gratuita.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una de las nuevas funciones m\u00e1s innovadoras para esta red, que tambi\u00e9n se espera para los pr\u00f3ximos meses, es un servicio de transmisi\u00f3n de v\u00eddeos en directo (\u00abstreaming\u00bb). Esto har\u00e1 que los usuarios de LiveCobo no solo puedan compartir contenidos est\u00e1ticos como fotos o v\u00eddeos, tambi\u00e9n <\/span><b>podr\u00e1n transmitir los velatorios y entierros en tiempo real<\/b><span style=\"font-weight: 400;\">, interactuando en directo con sus amigos y familiares a trav\u00e9s de mensajes de chat.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">LiveCobo de momento es una<\/span><b> red totalmente gratuita<\/b><span style=\"font-weight: 400;\">, ya que para ellos el dinero no es una prioridad. Pero est\u00e1n abiertos a la venta de publicidad a empresas del sector y es posible que m\u00e1s adelante haya funciones \u00abpremium\u00bb de pago.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque estos d\u00edas nos pueden traer tristeza y nostalgia, <\/span><b>LiveCobo espera inspirarnos un sentimiento de tranquilidad, paz y tambi\u00e9n de felicidad<\/b><span style=\"font-weight: 400;\">, ya que tenemos nuestra propia vida y la de nuestros allegados a\u00fan por disfrutar, y podemos mantener viva la memoria de los que ya no est\u00e1n.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se acerca el d\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente. Es una fecha para recordarles y honrar su memoria, bien c\u00f3mo para compartirlo con los que todav\u00eda pueden hacerlo. Adem\u00e1s de las visitas a los cementerios de todo<\/p>\n","protected":false},"author":1,"featured_media":107646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[181],"tags":[343,357],"class_list":["post-107645","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internet","tag-internet","tag-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Se acerca el d\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"internet,sociedad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Se acerca el d\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"698\" \/>\n\t\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-10-27T18:18:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-03-09T13:39:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Se acerca el d\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#article\",\"name\":\"C\\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias\",\"headline\":\"C\\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Todos-los-Santos.jpg\",\"width\":698,\"height\":457,\"caption\":\"Todos los Santos\"},\"datePublished\":\"2021-10-27T18:18:08+02:00\",\"dateModified\":\"2022-03-09T13:39:04+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#webpage\"},\"articleSection\":\"Internet, internet, Sociedad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/internet\\\/#listItem\",\"name\":\"Internet\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/internet\\\/#listItem\",\"position\":2,\"name\":\"Internet\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/internet\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#listItem\",\"name\":\"C\\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#listItem\",\"position\":3,\"name\":\"C\\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/internet\\\/#listItem\",\"name\":\"Internet\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/\",\"name\":\"C\\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias\",\"description\":\"Se acerca el d\\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\\u00f3n a los amigos y parientes que ya no est\\u00e1n entre nosotros f\\u00edsicamente\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Todos-los-Santos.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#mainImage\",\"width\":698,\"height\":457,\"caption\":\"Todos los Santos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\\\/#mainImage\"},\"datePublished\":\"2021-10-27T18:18:08+02:00\",\"dateModified\":\"2022-03-09T13:39:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias","description":"Se acerca el d\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/","robots":"max-image-preview:large","keywords":"internet,sociedad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#article","name":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias","headline":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos.jpg","width":698,"height":457,"caption":"Todos los Santos"},"datePublished":"2021-10-27T18:18:08+02:00","dateModified":"2022-03-09T13:39:04+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#webpage"},"articleSection":"Internet, internet, Sociedad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/#listItem","name":"Internet"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/#listItem","position":2,"name":"Internet","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#listItem","name":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#listItem","position":3,"name":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/#listItem","name":"Internet"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/","name":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias","description":"Se acerca el d\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#mainImage","width":698,"height":457,"caption":"Todos los Santos"},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/#mainImage"},"datePublished":"2021-10-27T18:18:08+02:00","dateModified":"2022-03-09T13:39:04+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias","og:description":"Se acerca el d\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos.jpg","og:image:width":698,"og:image:height":457,"article:published_time":"2021-10-27T18:18:08+00:00","article:modified_time":"2022-03-09T13:39:04+00:00","twitter:card":"summary_large_image","twitter:title":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet | El Digital de Asturias","twitter:description":"Se acerca el d\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2021\/10\/Todos-los-Santos.jpg"},"aioseo_meta_data":{"post_id":"107645","title":null,"description":"Se acerca el d\u00eda de Todos los Santos, y muchos de nosotros volvemos nuestra atenci\u00f3n a los amigos y parientes que ya no est\u00e1n entre nosotros f\u00edsicamente","keywords":[],"keyphrases":{"focus":{"keyphrase":"de","score":88,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase used in the URL.","score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Focus keyphrase in image alt attributes","description":"Focus keyphrase not found in image alt attribute(s). Add an image with your Focus keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},"additional":[{"keyphrase":"amigos","score":83,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase not found in image alt attribute(s). Add an image with your Keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"f\u00edsicamente","score":83,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase not found in image alt attribute(s). Add an image with your Keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"parientes","score":83,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase not found in image alt attribute(s). Add an image with your Keyphrase as alt text.","score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 21:44:16","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-10-27 17:44:00","updated":"2026-05-26 21:44:16"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/\" title=\"Internet\">Internet<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/\" title=\"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet\">C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Internet","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/internet\/"},{"label":"C\u00f3mo guardar los recuerdos de nuestros seres queridos en Internet","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/como-guardar-los-recuerdos-de-nuestros-seres-queridos-en-internet\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/107645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=107645"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/107645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/107646"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=107645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=107645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=107645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}